{"id":1180,"date":"2024-04-11T12:57:07","date_gmt":"2024-04-11T12:57:07","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=1180"},"modified":"2024-04-11T13:04:35","modified_gmt":"2024-04-11T13:04:35","slug":"newsletter-jeshua-net-april-2024","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-april-2024\/","title":{"rendered":"Newsletter Jeshua.net &#8211; April 2024"},"content":{"rendered":"\n<figure class=\"wp-block-table is-style-stripes has-medium-font-size\"><table class=\"has-text-color has-background has-link-color has-fixed-layout\" style=\"color:#16006f;background-color:#abb7c2c4\"><thead><tr><th><strong><strong>Mitteilung<\/strong><\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>Die Website unseres Verlags (eft-book.com) wurde gehackt. Wenn Sie dennoch B\u00fccher bestellen m\u00f6chten, k\u00f6nnen Sie dies \u00fcber diese E-Mail-Adresse tun: <a href=\"mailto:sales@eft-books.com\">sales@eft-books.com<\/a><\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Leser<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben auf unserer Webseite ein neues Channelings ver\u00f6ffentlicht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/die-mystische-verbundenheit-gleichgesinnter-seelen\/\">Die mystische Verbundenheit gleichgesinnter Seelen<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Jeshua, gechannelt durch Pamela Kribbe<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8222;Wir sind Eins. Gleichgesinnte Seelen sind in einer mystischen Einheit miteinander verbunden. Diese Einheit ist nat\u00fcrlich keine Einheit physischer Natur. Sie ist energetischer Art, und ihr f\u00fchlt diese Einheit als Liebe und als ein Wiedererkennen in eurem Herzen und als ein Aufgehoben-Werden aus der Schwere der irdischen Wirklichkeit. Ihr sehnt euch nach dieser Geistesverwandtheit und Verbindung. Ihr trefft durchaus auch Menschen in eurem Leben, mit denen ihr eine solche Verbindung f\u00fchlen k\u00f6nnt. Diese ist jedoch immer unvollst\u00e4ndig, denn ihr sucht zutiefst nach eurem eigenen Licht, nach eurem eigenen Kern des Christus-Lichts, das dabei ist, sich zu entwickeln und \u2013 besser noch gesagt \u2013 sich auszubreiten. Sie befreit sich in der irdischen Wirklichkeit nun mehr und mehr.<br>Die Anwesenheit von und die Verbindung mit Gleichgesinnten kann euch in diesem Prozess, in diesem Erwachen auf der Erde helfen und euch stimulieren, ist jedoch f\u00fcr sich selbst nicht das Ziel. Ihr geht den Weg allein, unterst\u00fctzt und ermutigt von Anderen \u2013 manchmal von der Erde, manchmal vom Himmel -, aber eure tiefste Aufgabe besteht darin, das Licht in euch selbst zu finden und es auf der Erde brennen und flie\u00dfen zu lassen. Das gibt euch die tiefste erreichbare Erleichterung: Erleichterung im Sinne des Loslassens schwerer Lasten, des Hervorkommens eures nat\u00fcrlichen, einzigartigen Wesens und Seins. Erleichterung zu erfahren bedeutet, dass die Lasten des Nicht-Seins, dessen, nicht zu sein, wer ihr wirklich seid, von euch abfallen. Ihr werdet nat\u00fcrlich. Ihr werdet Eins.&#8220;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Herzliche Gr\u00fc\u00dfe,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gerrit und Pamela<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Mitteilung Die Website unseres Verlags (eft-book.com) wurde gehackt. Wenn Sie dennoch B\u00fccher bestellen m\u00f6chten, k\u00f6nnen Sie dies \u00fcber diese E-Mail-Adresse tun: sales@eft-books.com Liebe Leser Wir haben auf unserer Webseite ein neues Channelings ver\u00f6ffentlicht. Die mystische Verbundenheit gleichgesinnter Seelen Jeshua, gechannelt durch Pamela Kribbe &#8222;Wir sind Eins. Gleichgesinnte Seelen sind in einer mystischen Einheit miteinander&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-april-2024\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1180","post","type-post","status-publish","format-standard","hentry","category-newsletter"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/1180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=1180"}],"version-history":[{"count":9,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/1180\/revisions"}],"predecessor-version":[{"id":1193,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/1180\/revisions\/1193"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=1180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=1180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=1180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}