{"id":1380,"date":"2025-07-17T08:35:09","date_gmt":"2025-07-17T08:35:09","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=1380"},"modified":"2025-07-17T08:37:41","modified_gmt":"2025-07-17T08:37:41","slug":"newsletter-jeshua-net-juli-2025","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-juli-2025\/","title":{"rendered":"Newsletter Jeshua.net \u2013 Juli 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Liebe Leser<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben auf unserer Webseite zwei neue Channelings ver\u00f6ffentlicht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/maria\/euch-selbst-lieben\/\" target=\"_blank\" rel=\"noreferrer noopener\">Euch selbst lieben<\/a><br><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Maria, gechannelt durch Pamela Kribbe<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8222;Das Wort \u201eLiebe\u201c wird oft und locker verwendet, doch seine wirkliche Bedeutung ist nicht direkt erkennbar. Was bedeutet es, dass ihr geliebt werdet? Es ist tief in eurem System verankert, euer Bestes zu geben, um f\u00fcr gut genug befunden zu werden, um gemocht und angenommen zu werden, um dazuzugeh\u00f6ren und als erfolgreich angesehen zu werden. Obgleich ihr \u2013 begrifflich in eurem Kopf zumindest \u2013 wisst, dass wahre Liebe bedingungslos ist, haben die meisten von euch bedingungslose Liebe wenig erfahren. Euch selbst Liebe zu geben, ist darum nicht selbstverst\u00e4ndlich und nicht einfach.<br>Heute m\u00f6chte ich euch einladen, innerlich Kontakt mit einer Quelle der Liebe aufzunehmen, die immer da ist. Ich m\u00f6chte, dass ihr nun die Energie dieser Quelle, diese Schwingung und das Gef\u00fchl, das mit ihr einhergeht, in eurem Inneren aufsucht \u2013 nicht auf der intellektuellen, sondern auf der emotionalen Ebene -, sodass ihr in Momenten, in denen ihr es schwer habt, in denen ihr in Selbstverurteilung, Zweifel, Angst, Verzweiflung feststeckt, direkt darauf zugreifen k\u00f6nnt.&#8220;<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/maria\/euch-selbst-lieben\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Euch selbst lieben<\/strong><\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/die-trennung-der-geschlechter\/\" target=\"_blank\" rel=\"noreferrer noopener\">Die Trennung der Geschlechter<\/a><br><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Jeshua, gechannelt durch Pamela Kribbe<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8222;<em>Heute m\u00f6chte ich \u00fcber einen alten Schmerz in euch sprechen, der immer noch aktuell und in eurem Bewusstsein lebendig ist. Sehr viele eurer t\u00e4glichen seelischen Schmerzen gehen auf einen Urschmerz zur\u00fcck, den ich hier den Schmerz des Getrenntseins nenne. Bei den meisten von euch ist dieser Urschmerz immer im Hintergrund eures Bewusstseins pr\u00e4sent. Oft denkt ihr, dass ihr diesen Urschmerz oder die Wunde des Getrenntseins durch Dinge au\u00dferhalb von euch selbst aufl\u00f6sen k\u00f6nnt. Ihr sucht nach der richtigen, passenden Arbeitsstelle, dem richtigen Geliebten oder dem richtigen Lebensstil, was auch immer das bedeutet, oder nach einer bestimmten Disziplin oder bestimmten Regeln, nach denen ihr leben k\u00f6nnt. In euch ist eine Wunde, eine L\u00fccke, eine Leere, die ihr zu f\u00fcllen versucht. Heute m\u00f6chte ich auf die Ursache oder den Ursprung dieser Leere eingehen<\/em>.&#8220;<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/die-trennung-der-geschlechter\/\" target=\"_blank\" rel=\"noreferrer noopener\">Die Trennung der Geschlechter<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Herzliche Gr\u00fc\u00dfe,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gerrit und Pamela<\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Liebe Leser Wir haben auf unserer Webseite zwei neue Channelings ver\u00f6ffentlicht. Euch selbst lieben Maria, gechannelt durch Pamela Kribbe &#8222;Das Wort \u201eLiebe\u201c wird oft und locker verwendet, doch seine wirkliche Bedeutung ist nicht direkt erkennbar. Was bedeutet es, dass ihr geliebt werdet? Es ist tief in eurem System verankert, euer Bestes zu geben, um&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-juli-2025\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1380","post","type-post","status-publish","format-standard","hentry","category-newsletter"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/1380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=1380"}],"version-history":[{"count":2,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/1380\/revisions"}],"predecessor-version":[{"id":1382,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/1380\/revisions\/1382"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=1380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=1380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=1380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}