{"id":1414,"date":"2025-11-05T23:01:24","date_gmt":"2025-11-05T23:01:24","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=1414"},"modified":"2025-11-05T23:01:24","modified_gmt":"2025-11-05T23:01:24","slug":"raum-fuer-euch-selbst","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/die-erde\/raum-fuer-euch-selbst\/","title":{"rendered":"Raum f\u00fcr Euch selbst"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Die Erde durch Pamela Kribbe\u00a0<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Menschen,&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ich bin die Stimme der Erde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich gr\u00fc\u00dfe euch alle von Herzen und ich reiche euch meine Hand. Ich brauche euch, um diesen Planeten wieder zu einem Paradies zu machen, einem Spielfeld, in dem alle einander in Freiheit, Freude und Gleichheit begegnen k\u00f6nnen. Ihr alle tragt dieses Gel\u00f6bnis in euch. Ganz tief im Innern wusstet ihr, als ihr auf die Erde kamt, dass ihr diese Saat hier auss\u00e4en wolltet: das Versprechen von Einheit, von einem Zusammenspiel in Gleichheit und Freude &#8211; der Menschen untereinander, aber auch zwischen der Natur und dem Menschen, das Zusammenspiel zwischen den Tieren, Pflanzen und Steinen \u200b\u200bund dem Menschen. F\u00fchlt diese Verhei\u00dfung, dieses Versprechen, f\u00fchlt die kraftvolle Lebensenergie darin. Das Versprechen ist nicht verloren, seine Hoffnung ist lebendig geblieben.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Einige von euch werden sagen: &#8222;Wir sind auf der Erde auf einen Irrweg geraten und daf\u00fcr tr\u00e4gt die Menschheit die Verantwortung&#8220;, aber zu dieser Historie geh\u00f6rt eine tiefer liegende Schicht, es geht hier um mehr als das. Aus der h\u00f6chsten Ebene heraus betrachtet, hat die Menschheit zugestimmt, bestimmte Energien auf der Erde und in dieser Sph\u00e4re zu erfahren und umzuwandeln, sie von innen heraus zu ver\u00e4ndern. Von der h\u00f6chsten Ebene aus gesehen seid ihr Lichtengel, Wesen der Einheit, die kommen, um die Energie von Zuhause, die Energie von Gott selbst hier auf der Erde zu verbreiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch auf eurem Weg hierher, dem Weg des Abstiegs, den die Inkarnation darstellt, habt ihr viele dichte und dunkle Energien kennengelernt, die ebenfalls im Kosmos leben und die darin ebenso ihre Daseinsberechtigung haben. Diese Energien sind gewisserma\u00dfen bei euch haften geblieben, ihr habt sie absorbiert, um sie sp\u00e4ter transformieren zu k\u00f6nnen. Doch dies habt ihr vergessen, da ihr auf eurem Abstiegsweg zum Teil den Kontakt zu der Quelle verloren habt, der ihr entstammt. Es hat Inkarnationen gegeben, in denen ihr euch so tief in das Nicht-Lichte, das Nicht-Einssein untergetaucht gef\u00fchlt habt, dass ihr nach eurem Empfinden den Weg verloren habt und in der Dunkelheit gleichsam versandet seid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fchlt dem einmal nach, wie dieser Fall in die Dunkelheit euch ber\u00fchrt hat, wie er euch in eurem Herzen gepeinigt hat. Und f\u00fchlt auch, wie gro\u00df und gro\u00dfartig ihr seid, dass ihr, als Engel, dies auf euch genommen habt. Denn irgendwann, nachdem ihr euch auf diese lange Reise der Inkarnationen begeben habt, wurde euch bewusst, dass es euch ein gro\u00dfes Opfer abverlangen w\u00fcrde. Dass es von euch erfordern w\u00fcrde, wirklich tief in die Dunkelheit einzutauchen, um so mit allen Energien vertraut zu werden, die im Kosmos leben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr habt dieses Opfer aus der Liebe zum Leben selbst erbracht. Ihr seid in den Tanz mit der Dunkelheit eingetreten, weil tief in euch ein Vertrauen lebt, ein Wissen, dass ihr Licht seid und dass ihr wieder zu diesem Licht zur\u00fcckkehren werdet. Ihr werdet es in euch selbst erstehen lassen und es so verbreiten. Und ihr tut dies dann nicht mehr nur in der Sph\u00e4re der Einheit, aus einer himmlischen Sph\u00e4re heraus, sondern hier, auf der Erde. Ihr werdet euch so stark daran erinnern, wer ihr seid, dass ihr das Licht <em>hier<\/em> verbreiten werdet. Selbst wenn ihr der erste und der einzige Mensch in eurer Umgebung seid, der dies tut! Ihr seid Pioniere des Lichts auf der Erde, das ist das Versprechen, das ihr in eurem Herzen tragt, das ist es, wer ihr sein wollt.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erkennt eure eigene Gr\u00f6\u00dfe und seht auch, dass ihr euch gerade dadurch manchmal <em>anders<\/em> f\u00fchlen k\u00f6nnt, wie ein fremdartiger Sonderling, ein Au\u00dfenseiter, der in der Schwingung dieser Welt nur schwer mitkommt, wo immer sie unter der Regie von Angst, Misstrauen, Argwohn und Kampf steht. Ihr alle kennt diese Energien von innen heraus. Wie alle Engel habt auch ihr von diesen negativen Energien eine tiefe Kenntnis gewonnen, doch ihr seid auf eurem inneren Weg nun so weit, dass ihr sie \u00fcberwinden m\u00f6chtet. Dass ihr nun die Verantwortung \u00fcbernehmen und wieder Raum f\u00fcr euer wahres Selbst, das Engelslicht schaffen wollt, das euch an euer wahres Zuhause erinnert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meine heutige Botschaft besteht darin, euch Wege aufzuzeigen, wie ihr diesen Raum wieder einnehmen k\u00f6nnt, den Raum, in dem euer wahres Selbst, euer urspr\u00fcngliches Licht, wieder flie\u00dfen kann. Warum f\u00e4llt euch dies so schwer?&nbsp;Das Leben fordert von euch, dass ihr eurer Natur folgt, dem, wer ihr urspr\u00fcnglich seid. Das ist tats\u00e4chlich die einzige Aufgabe, die ihr f\u00fcr das Leben auf der Erde mitgegeben bekommt. Seid wer ihr seid! Und das mag vielleicht einfach erscheinen, aber ihr m\u00fcsst schon in jungen Jahren einen sehr starken Gegenstrom aushalten, der euch vermittelt: &#8222;Sei <em>nicht<\/em> der, der du bist. Gehorche den bestehenden Vorschriften, Regeln, Vorstellungen, Normen, die in der Gesellschaft bestehen, in der ihr lebt&#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schon von klein auf habt ihr es mit einer Gegenstr\u00f6mung zu tun, die euch in eurem nat\u00fcrlichen Wesen und Sein entmutigt und euch von ihm abh\u00e4lt. Dieses nat\u00fcrliche Sein wird aus der inneren Inspiration gen\u00e4hrt. In jedem kleinen Kind, das auf der Erde geboren wird und aufw\u00e4chst, ist eine nat\u00fcrliche Inspirationsquelle: etwas, auf das sich das Verlangen des Kindes ganz nat\u00fcrlich und von selbst ausrichtet, etwas, das es von Natur aus gl\u00fccklich, inspiriert, freudig und enthusiastisch macht. Es w\u00e4re wunderbar, wenn diese nat\u00fcrliche Licht-Quelle des Kindes respektiert und alles daf\u00fcr getan w\u00fcrde, ihr freie Bahn zu geben. Doch bei vielen Menschen auf der Erde und in den etablierten Strukturen von Erziehung, Bildung und Gesellschaft, besteht gro\u00dfe Angst vor Spontaneit\u00e4t, Angst vor der Originalit\u00e4t, die in jedem Menschen lebt. Denn diese spontane Str\u00f6mung kann nicht in bereits bestehende Bahnen geleitet werden, sie ist unkalkulierbar und sie ist zudem innovativ. Sie ist pur und unvorhersehbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fchlt einmal, dass ihr diese Str\u00f6mung immer noch in eurem Bauch tragt. Seht sie einmal wie einen Springbrunnen aus Licht, sie ist immer noch da. Auch wenn ihr euch vielleicht von ihr entfernt habt, lebt diese Licht-Quelle noch immer in eurem Bauch: eure Originalit\u00e4t, eure Spontaneit\u00e4t, das, was ihr hier auf der Erde erleben, erfahren und geben m\u00f6chtet. Das seid ihr, das ist euer Seelenlicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und macht ihn nun gr\u00f6\u00dfer, diesen Springbrunnen aus Lichtblasen. Lasst ihn von eurem Bauch entspringen und euren Magen durchfunkeln und bis zu eurem Herzen und euren Hals str\u00f6men. Und f\u00fchlt einmal, wie sch\u00f6n und liebevoll diese Energie ist, wie unschuldig!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unbewusst habt ihr das Gef\u00fchl gewonnen, dass etwas mit dieser Str\u00f6mung nicht stimmt, weil ihr in eurer Umgebung Energien begegnet seid, die diese Str\u00f6mung in Bahnen lenken wollte, aber es waren nicht <em>eure<\/em> Bahnen, es waren die Bahnen anderer, der Tradition und oft auch Bahnen der Angst. Und so wurdet ihr entmutigt und denkt, dass mit dieser nat\u00fcrlichen Str\u00f6mung in euch etwas nicht stimmt. Auch ihr habt diese Str\u00f6mung als chaotisch, wild und unz\u00e4hmbar angesehen, aber das ist diese Str\u00f6mung nicht. Sie ist eine Str\u00f6mung, die ganz nat\u00fcrlich nach Gleichgewicht und Balance strebt. Sie ist eine Str\u00f6mung, die andere respektiert und gleichzeitig <em>euch<\/em> den Raum gibt, eure h\u00f6chsten und fantasievollsten Tr\u00e4ume zu verwirklichen. Hei\u00dft diese Str\u00f6mung nun wieder in eurer Gegenwart willkommen und vertraut ihr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses Vertrauen verlangt euch sehr viel ab, denn es bedeutet, dass ihr euch von den vorgebahnten Pfaden l\u00f6st, von dem, was die Menschen im Allgemeinen denken oder erwarten. Ihr habt diese Vorstellungen verinnerlicht, die Urteile von au\u00dfen sind inzwischen zu euren eigenen Urteilen geworden und leben nun in eurem Kopf und eurem Energiesystem. Wie oft verurteilt ihr eure eigene Energie? Es gibt oft etwas, das ihr wollt oder euch w\u00fcnscht, das spontan aus eurem Bauch heraus in euch aufkommt, und dann ist da ein \u00e4ngstliches Ich in eurem Kopf, das es voll Misstrauen oder Schamgef\u00fchl betrachtet, hin und her \u00fcberlegt und das so oft schon urteilt noch ehe die Stimme in eurem Bauch wirklich Gestalt hat annehmen k\u00f6nnen. Ihr haltet euch selbst unten, das wurde euch beigebracht.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und ich spreche kein Urteil \u00fcber jene unterdr\u00fcckende Energie aus, die es in eurer Kindheit gegeben hat, denn sie ist Teil der Sph\u00e4re auf der Erde, diese Energie <em>gibt<\/em> es. Und die Menschen, die sie an euch weitergeben &#8211; eure Eltern, eure Lehrer &#8211; wollen oft das Beste f\u00fcr euch. Sie sind oft gar nicht darauf aus, euch zu unterdr\u00fccken, sie sind selbst ebenfalls Tr\u00e4ger dieser unterdr\u00fcckenden Energie, weil auch sie in ihrer Kindheit gelernt haben, sich selbst zu unterdr\u00fccken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist ein Drama, das sich von Generation zu Generation fortsetzt, bis Menschen aufstehen, die sagen: &#8222;Stopp! H\u00f6rt auf, ich will da nicht mitgehen! Ich erinnere mich an etwas anderes &#8230; ich erinnere mich an eine Str\u00f6mung von Leben, von Licht, die gut ist, sauber, pur und die in mir wohnt, die in mir lebt und die da sein darf und die ein Leben verspricht, das nicht aus Angst und Misstrauen besteht, sondern ein Leben aus der Freude und \u00dcberf\u00fclle heraus und daraus, einander anzuerkennen, einander Raum zu geben, jedem mit seiner eigenen einzigartigen Energiestr\u00f6mung.&#8220;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Wunder ist, dass, wenn ihr das im anderen anerkennt, die gesamte Gesellschaft auf einer unendlich viel h\u00f6heren Ebene handeln und wirken wird, denn wenn jeder seinen eigenen Beitrag einbringt, passt das Puzzle ganz nat\u00fcrlich und von selbst zusammen. Alles ist dann aufeinander abgestimmt, muss nicht mehr vom Kopf aus, aus abstrakten Ideen heraus geregelt und reguliert werden. Vertraut der Spontanit\u00e4t in euch selbst, habt den Mut, mit den vorgebahnten Pfaden zu brechen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies ist nur m\u00f6glich, wenn ihr eure eigene G\u00fcte und euren eigenen Wert, eure eigene W\u00fcrde tief aus eurem Inneren heraus n\u00e4hren k\u00f6nnt. Daher m\u00fcsst ihr die von au\u00dfen kommende Ern\u00e4hrung oder Versorgung, die h\u00e4ufig in Form von Anerkennung, einem positiven Urteil also \u00fcber eure Leistungen oder Handlungsweisen erfolgt, loslassen und eure Nahrung wirklich im Innern suchen: &#8222;Was inspiriert mich? Was n\u00e4hrt mich?&#8220; Das ist Selbstwert &#8211; dass ihr euch diese Frage zu stellen wagt, ungeachtet dessen, was von au\u00dfen von euch erwartet wird, ungeachtet der Urteile, die ihr auf euch selbst abfeuert. Das bedeutet es, wirklich in euren eigenen Bauch hinein zu sinken und euch selbst offen zu begegnen: &#8222;Was lebt da in mir? Welche Emotionen wollen gesehen und gef\u00fchlt werden?&#8220;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denn es kann auch sein, dass, wenn ihr eure eigene Quelle, eure eigene Lichtquelle systematisch unterdr\u00fcckt habt &#8211; weil ihr euch dazu verpflichtet f\u00fchltet oder weil ihr das Gef\u00fchl hattet, dass sie nicht gut sei oder verboten sei -, auch tiefe Gef\u00fchle der Unzufriedenheit oder Trostlosigkeit, Einsamkeit, Kummer oder Traurigkeit entstanden sind, und diese wollen ebenfalls gesehen werden. <em>Alles<\/em> will gesehen werden, nicht nur eure Freude, eure Begeisterung, eure Inspiration, sondern auch diese w\u00fctenden, verletzten, gekr\u00e4nkten Anteile, diese traurigen Teile, die verzweifelten Teile. Das Wecken eurer eigenen Lebenskraft erfordert, dass ihr euch sowohl dem Licht in euch als auch der Dunkelheit zuwendet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und ich bitte euch, das nun zu tun &#8211; und ihr k\u00f6nnt dies f\u00fcr euch selbst jederzeit wiederholen: Schaut noch einmal diese Lichtquelle in euch an &#8211; diese Flamme in eurem Bauch, wo eure Originalit\u00e4t, eure Spontaneit\u00e4t lebt -, und f\u00fchlt dann gleichzeitig in euch selbst, wo ihr Angst vor dieser Str\u00f6mung, vor der Leidenschaft eurer Seele habt. Und schaut auch, ob ihr irgendwo in euch selbst eine Hemmung, eine Zur\u00fcckhaltung, eine Entmutigung wahrnehmt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gebt dem, was da &#8222;Nein&#8220; zu dieser inneren Str\u00f6mung in euch, zu eurer Seelenenergie sagt, nun eine Gestalt. Lasst es ein Mann, eine Frau oder ein Kind oder auch ein Tier sein, wenn ihr m\u00f6chtet. Es ist die Personifizierung eurer Angst, eures Selbsturteils, eures Nicht-Ja-Sagens zu euch selbst. Seht diese Person oder Gestalt mit einem offenen Herzen an, urteilt nicht \u00fcber sie. Schaut diese Gestalt mit den Augen des Engels in euch an, des h\u00f6chsten Lichts, das ihr seid. Dann ladet die Gestalt ein, n\u00e4her zu kommen. Fragt die Gestalt, was sie oder er sich w\u00fcnscht.&nbsp;Diese Person oder dieses Tier hat so lange so viel f\u00fcr euch getragen: \u00c4ngste, Wut, Entt\u00e4uschung, Einsamkeit&#8230; sie\/es verdient es, mit Achtung und Respekt behandelt zu werden. Sie oder es ist Teil eurer Sch\u00f6pfung. Nun ladet die Gestalt ein, zu euch zu kommen, und sagt ihr dann: &#8222;Ich werde dich nie wieder verlassen, ich erkenne dich an und du bist ein Teil von mir und du darfst da sein.&#8220;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lasst diese Person oder dieses Tier dann in eurem Bauch Platz nehmen, mitten in dieser Font\u00e4ne des Lebenslichts, das zu euch geh\u00f6rt. Und lasst die Gestalt durchstrahlt und \u00fcberflutet werden mit dem Licht, das euch geh\u00f6rt. Es ist ein sanftes Licht. Die dunkle Gestalt in euch nimmt genau das in sich auf, was sie jetzt h\u00e4ndeln kann, was sie jetzt braucht, was ihr gut tut, ihr braucht nichts zu forcieren.&nbsp;Das Licht in euch ist heilsam, ihr m\u00fcsst nichts daf\u00fcr tun, einfach nur &#8222;Ja&#8220; sagen zu&nbsp; dem, was in euch so gepeinigt ist und unterdr\u00fcckt wurde. So stellt ihr den nat\u00fcrlichen Fluss wieder her, die Str\u00f6mung eures Seelenlichts, und so bringt ihr ein St\u00fcck Himmel auf die Erde.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und das kann ein freudiger Prozess sein: immer wieder einen Schritt aus den Urteilen zur\u00fcckzutreten, die euch beigebracht wurden, und offen anzuschauen, was in euch f\u00fcr W\u00fcnsche, Tr\u00e4ume und Ideale leben, aber auch welche Angst und welcher Schmerz oder Widerstand und welche Dickk\u00f6pfigkeit. Auch das darf da sein. Wenn ihr dazu ebenso herzlich &#8222;Ja&#8220; sagen k\u00f6nnt wie zu eurem Licht und eurem Enthusiasmus, werdet ihr ein ganzer Mensch, ein Engel auf der Erde, und dann macht ihr ein tiefes Versprechen wahr, und das strahlt auch hin zu anderen aus. Es ist erf\u00fcllend und befreiend, auf diese Weise mit euch selbst umzugehen. Das Leben wird dann einfacher und flie\u00dft nat\u00fcrlicher und mehr von selbst.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr haltet nur dann an der Kontrolle \u00fcber euch selbst fest, wenn ihr Zweifel an eurer eigenen Natur habt, wenn ihr denkt, dass es sonst nicht gutgehen w\u00fcrde: &#8222;Wenn ich die Kontrolle loslasse, dann &#8230;&#8220; &#8211; darin sitzt eine Angst &#8211; &#8222;&#8230; dann habe ich es nicht mehr in der Hand&#8220;. Aber was da flie\u00dfen will, seid ihr selbst. Das ist eure eigene Natur, und die Vorstellung, dass daran etwas nicht stimmt, ist schon an sich ein Kontrollmechanismus, den ihr erlernt habt. Es kostet M\u00fche, das loszulassen, aber es beginnt damit, dass ihr euch f\u00fcr nichts mehr verurteilt, f\u00fcr was auch immer. Dass ihr &#8222;Ja&#8220; zu dem sagt, was in euch str\u00f6men m\u00f6chte, ob es sich nun schwierig anf\u00fchlt oder einfach und gl\u00fccklich. Es bedeutet es, euch f\u00fcr euch selbst zu entscheiden, euch selbst zu w\u00e4hlen und tats\u00e4chlich eure Engelsenergie in dieser Sph\u00e4re zu erden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich gr\u00fc\u00dfe euch alle und bin aus meinem Herzen mit euch verbunden. Ich bin selbst ein Lichtengel und erkenne und anerkenne den Lichtengel in euch. Immer.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a9&nbsp;Pamela Kribbe<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbersetzung:&nbsp;<a href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Yvonne Mohr<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Erde durch Pamela Kribbe\u00a0 Liebe Menschen,&nbsp; ich bin die Stimme der Erde. Ich gr\u00fc\u00dfe euch alle von Herzen und ich reiche euch meine Hand. Ich brauche euch, um diesen Planeten wieder zu einem Paradies zu machen, einem Spielfeld, in dem alle einander in Freiheit, Freude und Gleichheit begegnen k\u00f6nnen. Ihr alle tragt dieses&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/die-erde\/raum-fuer-euch-selbst\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1414","post","type-post","status-publish","format-standard","hentry","category-die-erde"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/1414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=1414"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/1414\/revisions"}],"predecessor-version":[{"id":1415,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/1414\/revisions\/1415"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=1414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=1414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=1414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}