{"id":534,"date":"2020-09-07T08:06:14","date_gmt":"2020-09-07T08:06:14","guid":{"rendered":"http:\/\/jeshua.net\/de\/?p=534"},"modified":"2020-09-07T08:06:14","modified_gmt":"2020-09-07T08:06:14","slug":"lebensfreude","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/die-erde\/lebensfreude\/","title":{"rendered":"Lebensfreude"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Die Erde, gechannelt durch Pamela Kribbe<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Menschen, ich bin die Stimme der Erde. Ich gr\u00fc\u00dfe euch alle und komme um \u00fcber Freude, \u00fcber Lebensfreude zu sprechen. Ihr alle sehnt euch danach, wo immer ihr euch auf eurem Lebensweg auch befindet.<br>Es kann leichtere und schwierigere Perioden in eurem Leben geben, und doch ist es unabh\u00e4ngig davon immer m\u00f6glich, eine Basis der Freude zu sp\u00fcren, sie durch euer Leben str\u00f6men zu f\u00fchlen.<br>Wie gelangt ihr zu dieser Basis, wie erschafft ihr sie? Es geschieht durch das Loslassen von Kontrolle. Durch Loslassen und Ergebung, Hingabe. Und <em>wo<\/em> gebt ihr sie hin? Ihr \u00fcbergebt sie an etwas, das gr\u00f6\u00dfer ist als euer Verstand, als euer Ego, als euer Wollen und Planen und Denken. Der Schritt zur Hingabe, zum Loslassen, ist scheinbar &#8211; so wurde euch suggeriert &#8211; ein Schritt ins Nichts, in eine Leere, eine Tiefe, ein dunkles Loch.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Irgendwann habt ihr zu glauben begonnen, dass es notwendig sei, mit eurem Verstand, mit eurem Willen Kontrolle \u00fcber euer Leben zu haben. Das ist sehr menschlich, denn nur der Mensch hat einen so gro\u00dfen Raum f\u00fcr seinen freien Willen. Verglichen mit anderen Wesen, mit nat\u00fcrlichen Wesen, habt ihr darin viel mehr M\u00f6glichkeiten und verleiten diese daher auch sehr dazu, dem Leben durch den Willen und das Denken eine bestimmte Form geben zu wollen. Wenn dies jedoch \u00fcberhandnimmt, wird euer Blick dadurch verengt &#8211; verengt auch durch das, was ihr aus eurer Perspektive heraus seht und wahrnehmt und durch die Vorstellungen, die ihr von anderen vermittelt bekommt. Ihr entwickelt einen Tunnelblick, wenn ihr allein auf euren Verstand, eure Ratio vertraut, auf das, was ihr kennt, und auf eure Pl\u00e4ne und Ideen, ohne dabei eure Gef\u00fchle und eure Natur hinzuzuziehen. Denn sie beide sind die Basis-Str\u00f6mung, die euch Freude schenkt: mitstr\u00f6men mit eurem Gef\u00fchl, eurer Natur, <em>eurer<\/em> <em>eigenen<\/em> Natur.<br>Wo eure Natur liegt und wo ihr sie findet, ist ein ganz anderer Bereich als euer Verstand und eure Ratio. Und es kann sich f\u00fcr Menschen, die ganz und gar mit der Vorstellung aufgewachsen sind, dass der Verstand das Wesentliche sei, das euch zum Menschen macht, ungewohnt und unangenehm anf\u00fchlen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lasst uns schauen, wo diese nat\u00fcrliche Str\u00f6mung in eurem K\u00f6rper zu finden ist.<br>Betrachtet einmal f\u00fcr euch selbst, welche Teile eures K\u00f6rpers aktiv werden, aktiviert werden, wenn ihr versucht, euer Leben zu kontrollieren. Seht einmal, was der Wille, euer Leben zu kontrollieren, auf k\u00f6rperlicher Ebene bewirkt. Schaut, ob ihr das in eurem K\u00f6rper feststellen k\u00f6nnt. Es geht oft einher mit Gedanken wie: &#8222;Das <em>muss<\/em> &#8230;, ich <em>will<\/em> &#8230;, es ist jetzt <em>Zeit &#8230;<\/em>, es ist jetzt <em>notwendig &#8230;<\/em>!&#8220; Es sitzt ein Druck, ein Drang dahinter, und auch eine Angst kann sich vielleicht dabei zeigen. Oft ist es eine Str\u00f6mung, die will, dass die Dinge schneller gehen als es m\u00f6glich ist. F\u00fchlt einfach, was diese Energiestr\u00f6mung mit euch macht.<br>Diese Str\u00f6mung hat mit eurem Kopf, mit der Energie des Verstandes zu tun. Ihr k\u00f6nnt sie zudem in eurem Sonnengeflecht f\u00fchlen, wo der Wille residiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nun sp\u00fcrt dem einmal nach, was geschieht, wenn ihr loslasst. Nehmt dazu in Gedanken etwas aus eurer t\u00e4glichen Wirklichkeit, das euch oft besch\u00e4ftigt, auf dem euer Fokus liegt oder in das ihr bereits viele Gedanken oder Sorgen oder Gr\u00fcbeleien investiert habt. Dann stellt euch vor, dass ihr diesbez\u00fcglich alle Erwartungen loslasst. <em>Lasst<\/em> <em>los<\/em> und nehmt dann wahr, wo in eurem K\u00f6rper euer Bewusstsein ganz von selbst hingeht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr k\u00f6nnt f\u00fchlen, wie ihr mit dem Loslassen tiefer in euren K\u00f6rper hinein sinkt. Wie ihr euch wieder eurer K\u00f6rperlichkeit bewusst werdet, eurer F\u00fc\u00dfe, eurer Beine, eurer Arme, eurer H\u00e4nde, eures Bauchs. Sp\u00fcrt die Ruhe, die der K\u00f6rper ganz nat\u00fcrlich ausstrahlt.<br>Der K\u00f6rper durchl\u00e4uft tagein tagaus viele Prozesse. Das Blut, das str\u00f6mt, die Nahrung, die verdaut wird, die Atmung, die Hautzellen, die sich erneuern. All diese Prozesse nehmen unaufh\u00f6rlich und in einem nat\u00fcrlichen Rhythmus ihren Gang. Alles in eurem K\u00f6rper hat einen nat\u00fcrlichen Rhythmus, genau wie in der lebendigen Natur au\u00dferhalb von euch.<br>Mitunter habt ihr einen solch sprunghaften Geist, der vorauseilen will und den Kontakt mit der Str\u00f6mung in euch verliert.<br>Euer Gef\u00fchl steht dem nat\u00fcrlichen Fluss, der nat\u00fcrlichen Str\u00f6mung des Lebens in euch viel n\u00e4her. Daher verbindet euch mit eurem Gef\u00fchl. Lasst Bewusstsein durch euren ganzen K\u00f6rper flie\u00dfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seht euch jetztnoch einmal den Aspekt oder Punkt an, \u00fcber den ihr so oft nachdenkt, das Problem, auf das ihr fokussiert seid, was auch immer es sein mag. Und erlaubt euch, einen Abstand dazu einzunehmen und zu f\u00fchlen, was es mit euch macht, wenn ihr zu euch sagt: \u201eIch wei\u00df nicht weiter damit, ich lasse es einfach ganz und gar gehen. Ich lasse es einfach ganz und gar los. Ich komme zu meiner Basis zur\u00fcck.\u201c Und das ist sofort auch erdend. Zu viel nachzudenken und kontrollieren zu wollen h\u00e4lt euch vom Jetzt fern. Und euch zu erden und loszulassen bringt euch zur\u00fcck in die Gegenwart, in das Hier und Jetzt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Habt den Mut, auf gr\u00f6\u00dfere Kr\u00e4fte zu vertrauen. Kr\u00e4fte, die gut und heilsam sind und die euch in eurem Leben begleiten, unterst\u00fctzen wollen, ohne dass ihr das immer mit den irdischen Sinnen wahrnehmen oder mit eurem menschlichen Verstand erfassen k\u00f6nnt. Diese Kr\u00e4fte sind \u00fcberall am Wirken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tieren und Pflanzenf\u00e4llt es leichter, diesen Fluss zuzulassen. Sie tun es ganz selbstverst\u00e4ndlich, weil sie nicht die Art von Denken haben wie die Menschen. Vertraut wieder diesem nat\u00fcrlichen Fluss der G\u00fcte und G\u00fctigkeit, der die gesamte Sch\u00f6pfung, alles Leben durchstr\u00f6mt, und h\u00f6rt auf euer Gef\u00fchl.<br>In den Momenten, wo ihr euch in eurem Leben festfahrt, seid ihr oft voll von Gedanken. Gedanken, dass etwas nicht gut l\u00e4uft, dass es anders h\u00e4tte laufen <em>sollen<\/em>, dass es anders h\u00e4tte laufen <em>k\u00f6nnen<\/em>. Ihr arbeitet euch selbst in einem mentalen Krampf hinein, doch die L\u00f6sung kommt niemals vom Verstand selbst, vom Denken. Die L\u00f6sung liegt immer im Loslassen, darin, einen Schritt zur\u00fcck zu treten. Und zu f\u00fchlen, dass ihr gut seid, so wie ihr seid. Dass es m\u00f6glich ist, Freude zu erleben, ein stilles Gef\u00fchl von Gut-Sein, selbst wenn es in eurem Leben Probleme gibt. Selbst wenn es Herausforderungen gibt, die euch viel abverlangen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr k\u00f6nnt diese Basis-Str\u00f6mung der Freude und G\u00fcte erleben, indem ihr wagt, loszulassen. Dies erfordert eine gewisse Disziplin. Nicht die Disziplin des Fokussierens und Anstrengens, sondern gerade die Disziplin des Mutes, dagegen vorzugehen. Gegen diese nat\u00fcrliche, instinktive Neigung, es l\u00f6sen zu wollen, es selbst zu tun und auch es besser zu wissen, zu denken, dass ihr die L\u00f6sung wisst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manchmal liegt die L\u00f6sung gerade jenseits des Horizonts dessen, was ihr sehen k\u00f6nnt, und kann diese L\u00f6sung nur zu euch kommen, wenn ihr zuerst loslasst. Und wenn ihr sp\u00fcrt, dass im Loslassen eine Art Entspannung stattfindet, eine Erleichterung vielleicht, dann wisst ihr, dass es richtig ist. Denn die Str\u00f6mung der G\u00fcte und G\u00fctigkeit im Universum, die Str\u00f6mung der Freude, erkennt ihr an eurem eigenen Gef\u00fchl.<br>Gef\u00fchle des Gl\u00fccks, der Entspannung und der Freude sagen euch, dass ihr mit dieser Str\u00f6mung Verbindung habt. Vertraut ihr, immer wieder. Auch wenn dies den Gesetzen des Verstandes widerspricht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nehmt regelm\u00e4\u00dfig Verbindung mit eurem K\u00f6rper auf. Schaut immer einmal bei euch selbst, ob ihr vollst\u00e4ndig in eurem K\u00f6rper pr\u00e4sent seid. Und erkennt in allem, wor\u00fcber ihr euch zu viele Sorgen macht und nachgr\u00fcbelt &#8222;Es gibt etwas Gr\u00f6\u00dferes, das mich tr\u00e4gt&#8220;. Es ist das Gro\u00dfe, das Gr\u00f6\u00dfere, das daf\u00fcr gesorgt hat, dass ihr, als Seele, jetzt hier auf der Erde seid, verk\u00f6rpert in einem menschlichen Leib. Und es ist dieses Gr\u00f6\u00dfere, das ihr mitnehmt auf die andere Seite, ins Jenseits, wenn ihr diesen K\u00f6rper loslasst.<br>Vertraut darauf, dass dieses Gr\u00f6\u00dfere auch <em>w\u00e4hrend <\/em>eures Lebens immer bei euch sein wird. Ihr k\u00f6nnt es Seele nennen oder ihr k\u00f6nnt es Gott nennen. Das ist ganz gleich. Aber die Sprache, die es spricht, ist eine der Freude und Entspannung. Und sobald ihr das f\u00fchlt, seid ihr in Kontakt mit der Essenz der Sch\u00f6pfung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich w\u00fcnsche euch allen Lebensfreude auf eurem Weg und den Mut, um zu wagen, loszulassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Channeling:\u00a0\u00a9<\/strong>\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.pamela-kribbe.net\/\" target=\"_blank\">Pamela Kribbe<\/a><br><strong>\u00dcbersetzung:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\">Yvonne Mohr<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Erde, gechannelt durch Pamela Kribbe Liebe Menschen, ich bin die Stimme der Erde. Ich gr\u00fc\u00dfe euch alle und komme um \u00fcber Freude, \u00fcber Lebensfreude zu sprechen. Ihr alle sehnt euch danach, wo immer ihr euch auf eurem Lebensweg auch befindet.Es kann leichtere und schwierigere Perioden in eurem Leben geben, und doch ist es&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/die-erde\/lebensfreude\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-534","post","type-post","status-publish","format-standard","hentry","category-die-erde"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=534"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/534\/revisions"}],"predecessor-version":[{"id":535,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/534\/revisions\/535"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}