{"id":540,"date":"2020-10-12T14:05:12","date_gmt":"2020-10-12T14:05:12","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=540"},"modified":"2024-08-10T07:46:29","modified_gmt":"2024-08-10T07:46:29","slug":"die-blumen-der-erde","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/maria-magdalena\/die-blumen-der-erde\/","title":{"rendered":"Die Blumen der Erde"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Maria Magdalena, gechannelt durch Pamela Kribbe<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Freunde und Freundinnen,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ich bin Maria Magdalena. Ich komme zu euch als eine Schwester, eine euch Gleichgestellte. Ich bin <em>eins<\/em> mit euch. F\u00fchlt mein Herz, meine Energie mitten unter euch. Ich bewege mich durch euren Kreis und freue mich \u00fcber diese Zusammenkunft hier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr seid die Blumen der Erde. Ihr tragt in eurem Wesen eine Sch\u00f6nheit von hoher Schwingung und eine Liebe f\u00fcr die Erde und f\u00fcr alles, was hier lebt &#8211; die B\u00e4ume, den Wind, das Gestein &#8211; alles das liebt ihr. Ihr seid mit der Gesamtheit der Erde verbunden. Ihr seid die Blumen der Erde, in eurer Ausstrahlung, in eurem Lachen, in eurem Blick.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr entsendet eine Schwingung, eine Freude und eine innere Entfaltung, die sich auf alles und alle auswirken, das und die daf\u00fcr offen sind. Es ist das innere Licht, das ihr in euch tragt, und ihr tut es der Welt kund und kommuniziert es mit ihr. Es strahlt aus euch heraus, es ist wer ihr seid. Je mehr ihr euch dieses innere Licht zu eigen macht, es mit vollem Bewusstsein genie\u00dft, es anerkennt und in euch selbst zulasst, desto deutlicher wird es wahrnehmbar f\u00fcr alle Wesen, denen ihr begegnet &#8211; f\u00fcr die Tiere, die Pflanzen und auch f\u00fcr die Menschen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber mitunter kann es f\u00fcr Menschen schwierig sein, auf euer Licht zu reagieren, denn es konfrontiert sie mit Teilen ihrer selbst, die nicht im Licht stehen, Teile, die sie oftmals verborgen halten m\u00f6chten. Euer Licht kann sie auf diese Teile in ihnen hinweisen und sie &#8222;brennend hei\u00df&#8220; ber\u00fchren, ohne dass ihr es wisst. Das Licht wirft in ihnen dann einen tiefen Schatten, macht sie der verlorenen Teile in sich selbst bewusst, und mitunter f\u00fchrt dies dazu, dass Menschen sich von euch zur\u00fcckziehen, weil sie das Licht nicht ertragen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich sehe, dass es euch schmerzt, wenn ihr diese Reaktion erlebt, und dass ihr euch manchmal f\u00fcr euer eigenes Licht sch\u00e4mt und euch fragt, ob euer Licht in dieser Welt denn willkommen ist. Viele von euch setzen sich dann selbst herab und ziehen das kostbare Licht ihrer Seele oft zur\u00fcck, das dazu bestimmt ist, hier auf der Erde zu leuchten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit der Natur aber seid ihr in der Lage, zu interagieren, denn die Natur ist offen f\u00fcr euer Licht, f\u00fcr eure Seelen-Energie. In der Natur f\u00fchlt ihr keine Barrieren, keinen Widerstand. Darum f\u00fchlen viele von euch sich so tief und emotional mit der nat\u00fcrlichen Welt verbunden, sei es das Pflanzenreich, das Tierreich oder das Reich der Steine. Hier k\u00f6nnt ihr eure Energie hervor str\u00f6men lassen, und das tut euch gut. Es entspannt euch, denn es ist nat\u00fcrlich f\u00fcr euch, euch zum Ausdruck bringen zu wollen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist nat\u00fcrlich f\u00fcr euch, euch zum Ausdruck zu bringen, <em>wo auch immer<\/em> ihr im Universum lebt. Doch hier auf der Erde erlebtet und erlebt ihr dabei immensen Widerstand &#8211; nicht nur in eurem jetzigen Leben, sondern auch in vorherigen Leben, denn ihr seid bereits zuvor auf der Erde gewesen. Dieser Widerstand hat einen so tiefen Eindruck bei euch hinterlassen, dass in euch nun eine Wachsamkeit und eine Tendenz besteht, zur\u00fcckzuweichen, euch furchtsam zur\u00fcckzuziehen. Durch diese Reaktion ist das Licht weniger in der Lage, in dem Ma\u00df auszustrahlen, wie es das k\u00f6nnte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses Zur\u00fcckziehen eures eigenen Lichts, eures eigenen Wesens, eurer Essenz schmerzt euch. Es ist eine widernat\u00fcrliche Bewegung. Es ist f\u00fcr euer Licht nat\u00fcrlich, zu strahlen und auszustrahlen, denn Licht will nach au\u00dfen leuchten &#8211; es will Erhellung und W\u00e4rme zu allem bringen. Darum ist es unnat\u00fcrlich, diese Bewegung zur\u00fcckzuhalten. Was geschieht, wenn ihr das dennoch tut? F\u00fchlt f\u00fcr einen Moment, was es mit euch macht, wenn ihr wenn ihr euer Licht zur\u00fcckzieht. Schaut, was mit eurem Licht, mit eurer nat\u00fcrlichen Kraft geschieht, wenn ihr die menschliche Welt betretet:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stellt euch vor, ihr wandert in der freien Wildnis. Ihr lauft mit beschwingten Schritten durch die Natur, ihr genie\u00dft die Luft, das Gr\u00fcn, den Boden unter euren F\u00fc\u00dfen, die Tiere und Pflanzen, die ihr um euch seht. Nehmt wahr, wie ihr euch in dieser Umgebung f\u00fchlt, was ihr in die nat\u00fcrliche Welt um euch herum ausstrahlt. Ihr seht alles, denn ihr habt die F\u00e4higkeit, auch die kleinsten Dinge wahrzunehmen &#8211; die Sch\u00f6nheit eines Bl\u00fctenblattes, eines Pilzes, eines kleinen Frosches. Ihr f\u00fchlt eine starke intuitive Verbindung mit dem Leben um euch herum, und dieses Leben sieht auch euch, es nimmt euch wahr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fchlt einmal, wie euch die B\u00e4ume, die Steine, die Pflanzen, die Tiere anschauen. Was sehen sie in euch, wie ihr da so gl\u00fccklich und sorglos umherlauft? Sie sp\u00fcren in euch ein h\u00f6heres Bewusstsein, denn ihr bringt das Kosmische Licht auf die Erde herab. Schaut, was es ihnen und allen Lebewesen macht, wenn ihr dieses Licht nat\u00fcrlich ausstrahlt. Lenkt eure Aufmerksamkeit einmal auf ein einzelnes Wesen, sei es ein Stein, eine Pflanze oder ein Tier, und schaut dann, was geschieht, wenn ihr euer Licht zu diesem Wesen hin str\u00f6men lasst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fchlt das Universum, das sie in euch sehen. Es macht sie gl\u00fccklich und froh, dass ihr da seid. Eure Energie ist kraftvoll und heilsam und es bringt einen Funken von Bewusstsein in die Natur. F\u00fchlt diese tiefe Verbundenheit mit der Erde, f\u00fchlt eure Kraft und eure Weisheit. Euer Herz ist sanft und eure Wahrnehmungen subtil. Ihr seid euch der verschiedensten Arten von Energiestr\u00f6mungen bewusst, und dennoch seid ihr auch kraftvoll. Ihr setzt eure F\u00fc\u00dfe fest auf den Boden, ihr geht mit festem Schritt und ihr wisst, wo ihr hin wollt. Ihr seid frei! Ihr seid unabh\u00e4ngig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nun geht weiter auf eurem Weg durch die Natur. Ihr kommt jetzt in die menschliche Welt. Stellt euch vor, dass ihr in zum Beispiel in eine Situation eintretet, in der alle m\u00f6glichen Menschen anwesend sind, die an kleinen Tischen sitzen oder miteinander reden, oder visualisiert euch selbst in einer Arbeitsumgebung. Worum es geht, ist, dass ihr eine menschliche Umgebung betrachtet und seht,was das mit euch macht. K\u00f6nnt ihr eure nat\u00fcrliche Energie halten, wenn ihr dort seid? Gibt es eine Umgebung in eurem t\u00e4glichen Leben, wo die Menschen in der Lage sind, die Energie zu empfangen, die ihr in der Natur ausstrahlt? Gibt es Menschen in eurer Umgebung, die eure Energie genauso gut empfangen k\u00f6nnen wie die Wesen in der Natur es tun?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es blockiert bei den vorherigen Bildern etwas in euch, weil es Situationen in eurer menschlichen Umgebung gibt, in denen ihr sp\u00fcrt: &#8222;Meine Energie str\u00f6mt hier nicht gut. Ich empfinde Furcht und Zweifel und das Bed\u00fcrfnis, mich zur\u00fcckzuziehen.&#8220; &nbsp;Schaut euch an, was dies auf k\u00f6rperlicher Ebene mit euch macht, und seht es euch voll Ruhe und Interesse an. F\u00e4llt kein Urteil dar\u00fcber. Schaut, wo eure Energie stagniert, wenn ihr in einer Umgebung seid, in der eure Energie nicht gut empfangen wird. Und fragt euch dann: &#8222;Was braucht es, damit meine Energie in diesem Teil von mir flie\u00dfen kann?&#8220;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt zwei M\u00f6glichkeiten: Entweder k\u00f6nnt ihr etwas in euch selbst ver\u00e4ndern oder aber ihr k\u00f6nnt euch aus dieser Situation entfernen. Sp\u00fcrt nach, ob ihr f\u00fchlen k\u00f6nnt, welches die bessere Wahl ist. Besteht in einer Umgebung, in der eure Energie <em>nicht<\/em> gut empfangen wird, das Potential zur Ver\u00e4nderung? Besteht in ihr eine M\u00f6glichkeit, die noch nicht genutzt wurde? Oder ist es Zeit, diese Umgebung loszulassen? Gibt es eine andere Umgebung, die euch lockt oder ruft? Ihr m\u00fcsst euch diese andere Umgebung nicht unbedingt vorstellen k\u00f6nnen, aber wenn es sie gibt, k\u00f6nnt ihr euch innerlich aus der Ferne mit ihr verbinden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was ich euch heute vermitteln m\u00f6chte, ist, dass ihr euch nicht mit weniger zufrieden geben m\u00fcsst als mit dem, was f\u00fcr euch das Beste ist. Wer ihr seid, euer nat\u00fcrliches, strahlendes Selbst, so wie ihr es in der Natur gesehen habt, muss in eurem t\u00e4glichen Leben da sein k\u00f6nnen. Dieses &#8222;Selbst&#8220; gibt euch Freude, ein Gef\u00fchl der Erregung, des Gl\u00fccks, der Resonanz und Harmonie mit eurer Umgebung, Harmonie. Dann seid ihr Teil des Ganzen &#8211; ihr gebt und ihr empfangt, das ist der nat\u00fcrliche Weg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn ihr das Gef\u00fchl habt, dass dies in eurer allt\u00e4glichen Umgebung nicht geht, habt keine Angst davor, etwas zu ver\u00e4ndern. Es ist nicht nat\u00fcrlich, ein beengtes, verkrampftes Leben zu leben und euch selbst verstecken zu m\u00fcssen. Sagt euch nicht: &#8222;Ach, das geht nicht anders, ich hab mich schon daran gew\u00f6hnt&#8220;. Es ist Zeit, etwas zu ver\u00e4ndern, und nicht nur f\u00fcr euch, sondern f\u00fcr die Welt und die menschliche Gesellschaft als Ganzes. Genau ihr seid es, die ein Beispiel f\u00fcr eine andere Schwingung sein k\u00f6nnen, f\u00fcr eine urspr\u00fcnglichere Art des Seins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erinnert ihr euch noch, wie ihr in der Natur gelaufen seid und euren K\u00f6rper gef\u00fchlt habt? Wie ihr in euren Bauch atmen konntet, wie ihr auf der Erde stehen konntet, mit beiden F\u00fc\u00dfen fest auf dem Boden? Ruft dieses Gef\u00fchl noch einmal wach! Sp\u00fcrt in eurem K\u00f6rper die Energie dieses Moments, des Friedens und der Freude. F\u00fchlt, wie ihr euch im unteren Teil eures K\u00f6rpers &#8211; eurem Bauch, eurem Stei\u00dfbereich, euren Beinen &#8211; von der Erde getragen f\u00fchlt. Wie es sich anf\u00fchlt, euch frei zu bewegen und euch nicht dessen zu sch\u00e4men, wer ihr seid. Das ist Erdung &#8211; das ist Willkommen-Sein &#8211; das ist Zugeh\u00f6rigkeit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was sehr oft mit euch geschieht, wenn ihr in einer menschlichen Umgebung auf Widerstand trefft, ist, dass ihr euch von euren Emotionen zur\u00fcckzieht und dadurch eure Energie sich fast automatisch in die obere H\u00e4lfte eures K\u00f6rpers verlagert. Ihr f\u00fchlt euch dann in eurem Leib nicht mehr wohl und zuhause und haltet oder zieht euch darum zur\u00fcck. Oft entstehen dadurch in euch verzerrte Gef\u00fchle wie Schmerz oder Angst, Wut, Entt\u00e4uschung und selbst Bitterkeit. Ihr denkt \u00fcber diese Emotionen: &#8222;Das sollte so nicht sein, das ist nicht richtig&#8220;, und zieht euch so vom urspr\u00fcnglichsten Teil eurer selbst zur\u00fcck. Aber die Emotionen, die in der Konfrontation mit der menschlichen Umgebung, der Gesellschaft entstehen, sagen euch etwas dar\u00fcber, wer ihr <em>wirklich<\/em> seid und was ihr am innigsten m\u00f6chtet. Darum ist es wichtig, in eurem Bauch zu bleiben, denn euer Bauch ist der Sitz dieser Emotionen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gerade Frauen wurden gelehrt, soziale Beziehungen voller Mitgef\u00fchl und Verst\u00e4ndnis zu betrachten. Ihr habt euch eine Art Dienstbarkeit zu Eigen gemacht, aber diese Art des Dienstes &#8211; ein Dienen in einer selbst-ausl\u00f6schenden Weise um des lieben Friedens willen und um Konflikte zu vermeiden &#8211; geh\u00f6rt nicht zu eurer Seelenenergie. Dies kann nur geschehen, wenn ihr euch sozusagen aus dem Bauch zur\u00fcckgezogen habt. Ihr seid dann gebend, aber nicht mehr empfangend. Und letztlich entsteht dadurch in euch eine Leere, ein Gef\u00fchl von Einsamkeit und Unzufriedenheit und nicht mit der Erde und mit eurer eigenen Leidenschaft, eurer Freude und Inspiration verbunden zu sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich m\u00f6chte euch bitten, euren Bauch wieder zu bewohnen und dort wieder zuhause zu sein. Seid eine irdische Frau oder ein irdischer Mann und traut euch, zu zeigen, was ihr f\u00fchlt, selbst wenn die Emotionen unb\u00e4ndig oder aufs\u00e4ssig sind. Denn sie sind Tr\u00e4ger der Wahrheit. Die Konflikte, die ihr mit eurer menschlichen Umwelt erlebt, sind aus gutem Grund da, sie machen euch bewusst, wer ihr wirklich seid. Indem ihr eure Emotionen anderen gegen\u00fcber auf eine <em>verantwortliche<\/em> Weise und voller Ehrlichkeit und Offenheit ausdr\u00fcckt, k\u00f6nnen auch die anderen etwas davon lernen und sich ihrer eigenen aufgestauten Emotionen bewusst werden. Auf diese Weise bringt ihr eine nat\u00fcrliche Str\u00f6mung auf die Erde zur\u00fcck.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich bitte euch, nun bewusst in euren Bauch hinab zu steigen. Lasst euer Bewusstsein hinab in den Bereich eures Beckens flie\u00dfen und lasst eure Wurzeln in Richtung der Erde gehen. Hier liegt eure ganz eigene Kraft, eure Einzigartigkeit. Lasst dann aus eurem Bauch ein Symbol heraufkommen, das euch sagt, was ihr jetzt braucht, um euch gut zu erden und mit eurem Seelenlicht hier anwesend zu sein. Es kann ein kraftvolles Tier erscheinen oder auch ein eher abstraktes Symbol oder ein Kind, ein Baum, eine Blume. Lasst es ganz von selbst in euch empor kommen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alles ist in Ordnung, denn ihr steigt tief in euren irdischen K\u00f6rper hinab und seid in der Lage, euch in euren K\u00f6rper hinein zu entspannen und zu sein wer ihr seid. Traut euch, euch selbst drau\u00dfen in der Welt zu zeigen, und vertraut dem, was dieses Symbol euch zeigen will. Es kann mitunter sehr kraftvoll sein wie ein Drache, Feuer, ein Schwert. Vertraut den Signalen von eurem K\u00f6rper, vor allem den Signalen eurer &#8222;niederen&#8220; Emotionen. Gerade diese tiefen Emotionen wollen euch den Weg zur\u00fcck in euren nat\u00fcrlichen Seinszustand zeigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn ihr nat\u00fcrlich seid, seid ihr genau richtig und geht es euch gut. So wie ihr wart, als ihr in der Natur spazieren gingt &#8211; eingestimmt, spontan, nat\u00fcrlich &#8211; das ist es, wer ihr wirklich seid. Die dunklen Emotionen entstehen, wenn eure nat\u00fcrliche Str\u00f6mung unterdr\u00fcckt ist. Gleichzeitig versuchen diese dunklen Emotionen euch zu sagen, dass ihr euch selbst verratet oder im Stich lasst. Sie sind ein Ersuchen von euch selbst, in eurem Leben das Gleichgewicht wieder herzustellen. Darum arbeitet mit diesen Emotionen zusammen. Bejaht sie, nehmt sie an und stellt die nat\u00fcrliche Balance und Str\u00f6mung wieder her. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich gr\u00fc\u00dfe euch von Herzen und ich bin euch dankbar f\u00fcr die Br\u00fccke, die ihr zwischen Himmel und Erde schlagt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a9&nbsp;Pamela Kribbe<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00dcbersetzung:&nbsp;<a href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Yvonne Mohr<\/a><\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Maria Magdalena, gechannelt durch Pamela Kribbe Liebe Freunde und Freundinnen, ich bin Maria Magdalena. Ich komme zu euch als eine Schwester, eine euch Gleichgestellte. Ich bin eins mit euch. F\u00fchlt mein Herz, meine Energie mitten unter euch. Ich bewege mich durch euren Kreis und freue mich \u00fcber diese Zusammenkunft hier. Ihr seid die Blumen&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/maria-magdalena\/die-blumen-der-erde\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-540","post","type-post","status-publish","format-standard","hentry","category-maria-magdalena"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=540"}],"version-history":[{"count":3,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/540\/revisions"}],"predecessor-version":[{"id":1241,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/540\/revisions\/1241"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}