{"id":572,"date":"2021-02-05T11:28:14","date_gmt":"2021-02-05T11:28:14","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=572"},"modified":"2021-02-05T11:28:14","modified_gmt":"2021-02-05T11:28:14","slug":"newsletter-jeshua-net-februar-2021","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-februar-2021\/","title":{"rendered":"Newsletter JESHUA.NET \u2013 Februar 2021"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Liebe Leser<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben auf unserer Webseite zwei neue Channelings ver\u00f6ffentlicht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/wovor-hast-du-angst\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wovor hast Du Angst?<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Jeshua, gechannelt durch Pamela Kribbe<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8222;In der Spannung oder Unruhe, die ihr erlebt, steckt nahezu immer ein Aspekt von Angst. F\u00fchlt das einmal. F\u00fchlt diese Energie der Angst. Duckt euch nicht davor weg, sondern schaut sie direkt an. Erkennt, dass Angst immer ein Fehlen von Bewusstsein ist. Wenn ihr daher mit eurem Bewusstsein zu der Angst geht, l\u00f6st sich dabei immer etwas. F\u00fcllt also diesen Ort in eurem K\u00f6rper mit eurem Bewusstsein und wisst, dass ihr dadurch etwas aufl\u00f6st. Sobald ihr die Angst \u00fcberwindet, indem ihr sie direkt anseht, werdet ihr freier als ihr es zuvor wart. Ihr gewinnt an Freiheit! F\u00fchlt diese Freiheit einmal! Wann immer ihr denkt, dass etwas nicht m\u00f6glich ist, dass es nicht geht, dass ihr bei etwas scheitert, dass diese Welt nicht f\u00fcr euch geeignet ist, habt ihr es innerlich mit einer Angst zu tun. Sie erz\u00e4hlt euch alles M\u00f6gliche, \u00fcberzeugt euch davon, dass diese oder Dinge nicht sein k\u00f6nnen, nicht m\u00f6glich sind. Es ist eure eigene Angst, die dann spricht. Aber ihr seid viel gr\u00f6\u00dfer als diese Angst, nur vergesst ihr das manchmal.&#8220;<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/das-herz-tor-zu-vielen-wirklichkeiten\/\" target=\"_blank\" rel=\"noreferrer noopener\">Das Herz: Tor zu vielen Wirklichkeiten<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Jeshua, gechannelt durch Pamela Kribbe<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8222;Ich bitte euch nun, euch auf euer Herz zu konzentrieren, auf den energetischen Bereich eures Herzens, mit eurem Bewusstsein in es hinein zu sinken, und es als einen Raum zu sehen oder zu f\u00fchlen. Das Herz ist nicht nur ein physisches Organ, es ist ein Tor zu ganz anderen Welten oder Dimensionen. Es ist auf intuitiver Ebene auch eine \u00d6ffnung zu vielen Wirklichkeiten.<br>Stellt euch vor, dass ihr im Zentrum eures Herzens sitzt. Dass ihr in diesem Raum anwesend seid. Vielleicht seht ihr auch einen sch\u00f6nen Ort um euch, in der Natur oder in einem Geb\u00e4ude, einem Tempel oder einen Ort, der sich f\u00fcr ihr gut anf\u00fchlt.<br>Nun stellt euch vor, dass ihr eine Flamme oder eine Fackel in den H\u00e4nden haltet. W\u00e4hrend ihr sie haltet, f\u00fchlt, wie sie mit eurem Herzen verbunden ist. Sie ist euer Lebensfeuer. Sie enth\u00e4lt auch eure Seelenkraft, eure spezifischen Talente, die ihr hierher mitbringt. Schaut euch das Feuer, die Flamme einmal genau an. Es ist eine einzigartige Flamme, sie geh\u00f6rt euch. Schaut einmal, ob ihr darin verschiedene Farben oder eine dominierende Farbe seht. Und sp\u00fcrt nach, was sie bedeutet. Wof\u00fcr steht diese Farbe, diese Flamme, worum handelt es sich bei ihr? Welche Art von Energie kommt ihr in dieser Welt geben oder teilen?<br>Konzentriert euch darauf und f\u00fchlt, wie es auch euer tiefster Wunsch ist, diese kostbare Energie eures Herzens auszus\u00e4en und zu teilen. Nehmt Kontakt mit dieser Flamme, dieser Energie auf, und lasst sie durch euer gesamtes Energiefeld flie\u00dfen.&#8220;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Herzliche Gr\u00fc\u00dfe<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pamela und Gerrit<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Liebe Leser Wir haben auf unserer Webseite zwei neue Channelings ver\u00f6ffentlicht. Wovor hast Du Angst? Jeshua, gechannelt durch Pamela Kribbe &#8222;In der Spannung oder Unruhe, die ihr erlebt, steckt nahezu immer ein Aspekt von Angst. F\u00fchlt das einmal. F\u00fchlt diese Energie der Angst. Duckt euch nicht davor weg, sondern schaut sie direkt an. Erkennt,&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-februar-2021\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-572","post","type-post","status-publish","format-standard","hentry","category-newsletter"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=572"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/572\/revisions"}],"predecessor-version":[{"id":573,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/572\/revisions\/573"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}