{"id":592,"date":"2021-05-06T12:50:54","date_gmt":"2021-05-06T12:50:54","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=592"},"modified":"2021-05-06T12:50:54","modified_gmt":"2021-05-06T12:50:54","slug":"der-moment-der-wahl","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/der-moment-der-wahl\/","title":{"rendered":"Der Moment der Wahl"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Pamela channelt Jeshua<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Menschen,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ich bin Jeshua und ich verbinde mich mit euch aus dem Herzen des Christus-Bewusstseins.<br>Das Christus-Bewusstsein ist ein Energie-Feld, es ist eine Einheit, zu der ihr alle geh\u00f6rt &#8211; ganz gleich, ob euch dies bewusst ist oder nicht. Wir alle sind durch <em>ein<\/em> pulsierendes Herz, <em>einen<\/em> Atemzug verbunden, der die gesamte Sch\u00f6pfung durchzieht.<br>Wir gr\u00fc\u00dfen euch. Ihr seid nicht allein, ihr seid alle mit diesem Ganzen verbunden. Ihr geh\u00f6rt ihm an, in jedem Moment, bei jedem Schritt eures Lebens. Wir gr\u00fc\u00dfen euch. Wir verbinden uns mit euch, wir erkennen und wir lieben euch und senden euch unser Licht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr braucht mitunter eine R\u00fcckenst\u00e4rkung, denn das Leben auf der Erde in einem physischen K\u00f6rper ist bisweilen recht schwierig. Ihr m\u00fcsst mit Unbehagen umgehen, mit der Schwere und Dichte des K\u00f6rpers und mit den \u00c4ngsten und Illusionen, die zu dieser Seins-Dimension geh\u00f6ren. Dennoch hat es eine Zeit gegeben, in der ihr f\u00fcr euch gew\u00e4hlt habt, in diese Dimension, in die Dualit\u00e4t von Licht und Dunkelheit hier auf der Erde hinabzusteigen.<br>Geht einmal dorthin, zu diesem Moment zur\u00fcck. Einerseits liegt er Jahrhunderte \u00fcber Jahrhunderte, Millionen von Jahren zur\u00fcck. Andererseits ereignet er sich in jedem Moment und trefft ihr diese Wahl immer aufs Neue.<br>Geht zu dem Moment, wo ihr in eurer vollen Kraft steht: Ihr zweifelt nicht an euch. An dem zu zweifeln, wer ihr seid, ist euch noch nicht einmal in den Sinn gekommen, Zweifel ist euch fremd. Ihr seid, wer ihr seid, bedingungslos. Ihr seid strahlendes, leuchtendes Licht. Ihr kennt noch nichts anderes als das Licht, das ihr seid. Ihr zweifelt nicht an euch selbst, ihr seid euch eurer sicher. Ihr habt nicht das Gef\u00fchl, euch daf\u00fcr entschuldigen zu m\u00fcssen, wer ihr seid. Ihr <em>seid<\/em> einfach. F\u00fchlt die Liebe, die in dieser, eurer Str\u00f6mung ist, das unbek\u00fcmmerte Wesen, das entdecken und erforschen will und sich ganz offen und spielerisch wie ein Kind in Erfahrungen hineinbegibt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dann f\u00fchlt von eurem Herzen aus die Dimension der Erde: W\u00e4hrend ihr dieser unbek\u00fcmmerte Engel seid, f\u00fchlt ihr aus der Ferne die Dimension der Erde und die Gegenwart der Energien dort.<br>Eure Aufmerksamkeit wird dort hingezogen. Etwas winkt euch von dort. Mit einer gewissen Neugier und Offenheit wendet ihr euch der Erde zu. Etwas verlockt euch. Etwas in euch m\u00f6chte an diesem Ort sein. Ihr wisst noch nicht genau, was euch erwartet. Aber irgendwann kommt ein Moment, an dem ihr eine Wahl trefft, an dem ihr beschlie\u00dft, zu inkarnieren, eine Form anzunehmen, etwas von eurer Grenzenlosigkeit aufzugeben, damit ihr etwas anderes erfahren k\u00f6nnt, etwas, das ihr noch nicht kennt. Man kann tats\u00e4chlich sagen, dass in euch ein gewisses Verlangen nach <em>Unwissenheit<\/em> lebt. Ihr m\u00f6chtet die Dinge <em>anders<\/em> erleben k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stellt euch nun einmal vor, wie ihr zum ersten Mal eine Form, einen K\u00f6rper annehmt:<br>Anfangs seid ihr ein Bewusstsein, das grenzenlos ist. Ihr fragt euch nicht, wo ihr selbst beginnt und aufh\u00f6rt und wo der andere beginnt. Ihr <em>seid<\/em> einfach.<br>Stellt euch vor, dass ihr euch nun in die Form begebt und einen K\u00f6rper habt. Vielleicht ist es ein menschlicher K\u00f6rper, vielleicht seht ihr etwas ganz anderes. Neben der Spannung und der Abenteuerlichkeit des Neuen f\u00fchlt ihr euch jetzt auf einmal beklommen. Denn ein St\u00fcck eures Lichts scheint von euch genommen zu sein. Pl\u00f6tzlich f\u00fchlt ihr euch in euch selbst eingeschlossen, es gibt so etwas wie <em>euch<\/em> und alles andere <em>au\u00dferhalb<\/em> von euch.<br>Euer Gottesfunke ist hinabgestiegen in die Materie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Sinn all dessen ist, euren eigenen Gottesfunken zu <em>erkennen<\/em> &#8211; <em>in<\/em> der Materie. Aber bevor dies geschehen kann, m\u00fcsst ihr euch der Realit\u00e4t von Angst, Illusion und Unwissenheit stellen. Dennoch habt ihr dies gew\u00e4hlt, denn nichts anderes schenkt euch eine so tiefe Erf\u00fcllung, wie euren Gott-Funken in der Materie keimen zu lassen. Ihm dort Form zu geben. Ihn dort zu erleben. Auf eine \u00e4u\u00dferst sch\u00f6pferische Weise. Ihr k\u00f6nnt euch das vielleicht nicht vorstellen, weil ihr doch so oft das Gef\u00fchl habt, zu sehr in der Form und Dichte der Materie gefangen zu sein. Aber es liegt ein unglaubliches Versprechen darin, in der Form zu sein, inkarniert zu sein.<br>Nach der Erf\u00fcllung eben dieses Versprechens, dieser Verhei\u00dfung seid ihr alle auf der Suche: Dem Gott-Funken in eurem K\u00f6rper Gestalt zu geben und im Kontakt mit anderen um euch herum, die alle einen Teil von Gott verk\u00f6rpern und ihren eigenen Funken in sich leuchten zu f\u00fchlen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der erste Schritt zur \u00dcberwindung von Angst, Illusion, Schwere und Widerstand besteht darin, ihr Daseinsrecht anzuerkennen. Habt Respekt vor dieser gro\u00dfen Kraft. Denn <em>auch sie<\/em> ist eine sch\u00f6pferische Kraft. Sie ist <em>eine<\/em> Polarit\u00e4t der Dualit\u00e4t, in der ihr lebt. Betrachtet Angst einmal auf eine neutrale Weise.<br>Angst kann euch \u00fcberfluten, euch den Atem nehmen, euch in die Dunkelheit versetzen. Doch sie ist ein Teil der Sch\u00f6pfung und treibt euch voran, denn Angst zwingt euch dazu, euch tief innerlich mit euch selbst zu beraten, eine enorme Tiefe in euch selbst zu finden, die ihr nicht einmal hattet, als ihr dieser bedingungslose Engel im Himmel wart. Angst treibt euch weiter, in eure Tiefe hinein, aber auch in eure Weite und Ausdehnung. Ihr seid Sch\u00f6pfer von etwas Neuem. F\u00fchlt auch einmal die Sch\u00f6nheit, das Abenteuer darin. Ihr seid G\u00f6tter. Ihr habt es gewagt, euch in dieses Abenteuer zu begeben. Hab Respekt davor. Ihr seid G\u00f6tter. In der einen Hand haltet ihr die Dunkelheit, in der anderen Hand haltet ihr das Element Licht. Und ihr wolltet hier eine Verschmelzung, eine Alchemie erwirken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Schl\u00fcssel zum \u00dcberwinden der Angst in euch selbst besteht darin, Frieden mit dieser dunklen Kraft zu schlie\u00dfen, die es in dieser Dimension <em>gibt<\/em>. Sie ist ein Teil von euch, ihr habt sie euch erw\u00e4hlt. Wenn es daher eine Angst in eurem Leben gibt, begr\u00fc\u00dft sie. Versucht nicht, sie fortzuschieben. Denn je mehr ihr euch gegen sie wehrt, desto gr\u00f6\u00dfer wird sie. Ihr spielt dann zwei Polarit\u00e4ten gegeneinander aus und diese werden dadurch immer nur noch st\u00e4rker. Wenn ihr versucht, die Angst vom Licht aus zu bek\u00e4mpfen, dann erweist ihr ihr nicht die Ehre, die ihr zukommt. Angst hat ein Daseinsrecht, und sobald ihr dies f\u00fchlen k\u00f6nnt, ist eure Angst bereits weitgehend vorbei. Denn Angst h\u00e4lt euch besonders dann im Bann, wenn ihr sie loswerden wollt, wenn ihr euch gegen sie wehrt, wenn ihr sie nicht wollt. Wenn ihr ihr das Existenzrecht verweigert. Dann wird die Angst noch h\u00e4rter an eure T\u00fcr klopfen und euch wirklich qu\u00e4len. Sobald ihr euch in den Kampf gegen die Angst begebt, erkennt, dass ihr tats\u00e4chlich im Begriff seid, euch selbst zu verlieren, und auf diese Weise wird die Angst euch besiegen. Sie ruht nicht, bis ihr Existenzrecht anerkannt wurde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt einen Weg, Verbindung mit der Angst aufzunehmen, und das ist der Weg des Christus-Bewusstseins. Der Weg des Mitgef\u00fchls, des reinen, neutralen Bewusstseins. Dem, was ihr als negativ empfindet, kein Urteil, keinen Widerstand entgegenzusetzen.<br>Das ist die Kraft, die ihr jetzt in eurem Leben geb\u00e4rt, die Christus-Energie. Sie kann die Angst umh\u00fcllen und ihr dabei keine Gewalt antun. Dadurch meistert ihr die Angst: indem ihr sie dasein lasst, aber ohne dabei von ihr aufgezehrt oder absorbiert zu werden.<br>Das ist die eigentliche Bedeutung der Lichtarbeit. Licht zu sein bedeutet nicht, dass ihr immer das Richtige tut, hochgesteckte Ideale hegt und versucht, sie diszipliniert zu verwirklichen. Das alles sind falsche Bilder vom Licht. Ihnen liegt die Vorstellung zugrunde, dass ihr im Kampf gegen die Dunkelheit seid und dass sie niedergeschlagen werden muss, dass sie aus der Welt verschwinden muss. Aber was in dieser Dimension tats\u00e4chlich vor sich geht, ist viel mystischerer Natur. Ihr seid auf einer tiefgreifenden Ebene dabei, diese beiden Energien von Licht und Dunkelheit miteinander zu verschmelzen. Sie zusammenzuf\u00fcgen in einem Tanz, der die Sch\u00f6pfung unendlich bereichert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich m\u00f6chte euch bitten, Erbarmen mit euren eigenen \u00c4ngsten, mit eurer eigenen Negativit\u00e4t zu haben. Seid sanft mit ihr, schmiegt sanft eure H\u00e4nde um sie herum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stellt euch jetzt einmal vor, ihr sp\u00fcrt eure Angst in eurem K\u00f6rper oder in eurem Energiefeld und ihr umarmt sie mit der Energie puren Bewusstseins. Ohne Widerstreben, ohne Widerstand, sondern indem ihr einfach nur bei dieser Negativit\u00e4t, dieser Angst pr\u00e4sent seid. Sagt ihr: &#8222;Du darfst da sein.&#8220; Gebt ihr den Raum daf\u00fcr. &#8222;Du darfst bei mir sein, du geh\u00f6rst zu mir, du bist ein Teil von mir. Ich nehme es gern auf mich.&#8220; F\u00fchlt dann den Raum, den euch dies gibt. Ihr m\u00fcsst nicht mehr gegen die Angst oder Negativit\u00e4t ank\u00e4mpfen, ihr m\u00fcsst in Bezug auf sie nicht mehr so \u200b\u200bangespannt sein. Lasst die Angst ihre Rolle <em>spielen<\/em>. F\u00fchlt, dass euch dies Raum gibt und euch gr\u00f6\u00dfer macht, und dann f\u00fchlt das Licht in&nbsp; euch selbst. F\u00fchlt das Licht in euch selbst und seht, wie es einfach zur selben Zeit in euch bestehen kann. F\u00fchlt wieder den urspr\u00fcnglichen Engel, der so ungebunden und frei war, und lasst sein Funkeln durch eure Aura str\u00f6men.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses bedingungslose Da-sein, dieses Ja-sagen zu allem, was in euch lebt, dunkel oder hell, <em>das<\/em> bewirkt die Ver\u00e4nderung. <em>Das<\/em> bewirkt wirkliche Ver\u00e4nderung in eurem Leben. Mit dem pr\u00e4sent zu sein, wer ihr seid. Begr\u00fc\u00dft euch selbst, jetzt, in diesem Moment. Seht die Vielzahl von Energien in euch, wie sie euch durchstr\u00f6men, und begr\u00fc\u00dft euch selbst. &#8222;Ja, ich bin da. Ich darf sein, wer ich bin. Es ist ein Bewusstsein in mir, das alles umfasst und Ja sagt: Ich sage Ja.&#8220; Und dieses Bewusstsein ist es, das ich, Jeshua, euch mitgebracht habe. Es ist das Ja-Bewusstsein und es umfasst alles, das Helle und das Dunkle, die Angst und die Liebe, alle Emotionen. Dieses Bewusstsein l\u00e4sst alles <em>da sein<\/em>. Ihr seid so sehr gewohnt, etwas zu <em>tun<\/em>. Sobald ihr Blockaden begegnet, m\u00f6chtet ihr dagegen etwas <em>tun<\/em>. Aber das ist eine Kampfhaltung, das l\u00f6st es nicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Worum es geht, ist <em>sein<\/em> zu lassen. Und dieses Sein-lassen, euch dessen bewusst zu sein, was da ist, ist nicht Passives. Es ist die gr\u00f6\u00dfte Kraft, die es gibt. Es ist die Kraft, die alles aufbricht, die sowohl das Licht als auch das Dunkle umfassen kann und sie daher zusammenflie\u00dfen lassen kann. Dies ist die Kraft der Christus-Energie. Und sie geh\u00f6rt nicht Mir, sie geh\u00f6rt Euch Allen. Sie ist das Feld, das uns <em>tr\u00e4gt<\/em>. Der urspr\u00fcngliche Atem Gottes, der Sch\u00f6pfung. Und ihr k\u00f6nnt euch zu jeder Tageszeit mit diesem Bewusstsein verbinden. In dem Moment, wo ihr das Gef\u00fchl habt, mit euch selbst zu k\u00e4mpfen, k\u00f6nnt ihr Frieden atmen, k\u00f6nnt ihr f\u00fcr euch w\u00e4hlen, alles so zu lassen, wie es gerade ist. Euch <em>ent<\/em>-spannen. Denn das gr\u00f6\u00dfte Problem sind oftmals nicht die negativen Emotionen, die ihr erlebt, sondern eure Einstellung ihnen gegen\u00fcber, euer Widerstand gegen sie. Ihr wollt sie bek\u00e4mpfen, ihr wollt sie aufl\u00f6sen. Und diese Haltung ist eine des Kampfes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gerade wenn sich euch das Negative, wie ihr es nennt, zeigt, geht es darum, es <em>sein<\/em> zu lassen, es anzunehmen, ihm Raum zu geben. Genau das nimmt ihr die Sch\u00e4rfe. Das ist das Paradoxon. Das &#8222;Nichtstun&#8220; erschafft Raum daf\u00fcr, dass die Energien wieder flie\u00dfen k\u00f6nnen. Denn keine einzige Energie, kein einziges Gef\u00fchl ist von Dauer. Gerade wenn das Licht eures Bewusstseins darauf scheint, wird es sich bereits aus sich selbst heraus transformieren. Ihr m\u00fcsst das nicht <em>tun<\/em>. Wenn in euch Angst ist und ihr Ja zu ihr sagt, <em>wirklich<\/em> Ja zu dieser Angst sagt, &#8222;Du darfst da sein\u201c, dann transformiert sie sich.<br>Es entsteht dann eine Freude in euch, dass ihr euch das erlaubt. Ihr habt dann ein Gef\u00fchl des Mitgef\u00fchls f\u00fcr euch selbst und ihr denkt: &#8222;Wir kommen wirklich zusammen, ich und meine Angst&#8220;. Und ihr k\u00f6nnt dann bereits sehen, dass sich die Energie in euch bereits verschiebt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das gleiche kann geschehen, wenn ihr w\u00fctend seid. Wenn ihr w\u00fctend seid und Ja dazu sagt, dann hat die Wut nichts mehr, gegen das sie sich wehren muss. Sie kann einfach da sein. &#8222;Du bist w\u00fctend&#8220;, sagt ihr dann zu euch selbst, und dann wird ein Punkt kommen, an dem die Wut nicht weitergehen kann. Denn sie hat dann nichts mehr, gegen das sie sich wehren muss, und indem sie sich nun n\u00e4hren lassen kann, l\u00e4sst die Wut nach und macht Platz f\u00fcr etwas anderes. Meist einer Trauer und einem intensiven Schmerz, entstanden dadurch, nicht gesehen zu werden. Nicht anerkannt zu sein. Wut deutet fast immer auf einen tieferen Schmerz in eurer Seele hin. Und sobald ihr diesen seht, k\u00f6nnt ihr Ja <em>dazu<\/em> sagen. K\u00f6nnt ihr <em>dem<\/em> euer Bewusstsein zuwenden &#8211; und sagen &#8222;<em>Ich<\/em> sehe dich&#8220; &#8222;<em>Ich<\/em> erkenne dich an.&#8220; Dann kann Raum f\u00fcr Freude sein oder einfach f\u00fcr ein Gef\u00fchl des Friedens mit euch selbst. Auf diese Weise verwandelt ihr Negativit\u00e4t in euch selbst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch diese Energien als negativ und positiv zu bezeichnen, ist unrichtig, unzureichend &#8211; was ihr dann selbst auch f\u00fchlt. Gerade in der Dynamik und im Wechsel zwischen beiden entsteht etwas Wundersch\u00f6nes, eine Alchemie im Bewusstsein. Denn wenn ihr nicht so w\u00fctend gewesen w\u00e4rt, wie h\u00e4ttet ihr dann von diesem zugrunde liegenden Schmerz und Kummer erfahren? Und wie k\u00f6nntet ihr ihn und euch dann bejahen und best\u00e4rken und die Liebe geben, die ihr braucht? Denn selbst die negativsten Emotionen in euch haben euch etwas zu sagen, sie tragen einen verborgenen Schatz in sich. Sie kommen, um ihn euch zu bringen, daher verurteilt sie nicht, wirkt mit ihnen zusammen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Energie des Erbarmens und des Mitgef\u00fchls, die Energie dessen, einfach nur da zu sein und Ja zu sagen, liegt in eurer aller Herzen. Es tut uns weh zu sehen, wie ihr gerade euch selbst diese Energie oft entsagt, wo ihr sie dagegen einem anderen sehr wohl geben k\u00f6nnt. Geht innerlich der Frage nach, warum ihr das tut. Dem liegen tiefe \u00c4ngste zugrunde, die Angst davor, ganz f\u00fcr euch selbst da zu sein, den Raum einzunehmen, der euch geh\u00f6rt. Seht euch diese \u00c4ngste an und sagt Ja zu ihnen. Es ist euer tiefster, innigster Teil, dem ihr da gegen\u00fcbersteht. Wenn ihr Ja sagt, kann Entspannung eintreten und k\u00f6nnt ihr eure \u00c4ngste einfach da sein lassen und ist Raum f\u00fcr die Transformation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr liegt uns so sehr am Herzen. Ich spreche hier im Namen vieler. Viele Seelen auf unserer Seite sind mit euch verbunden. Sie sind eure Br\u00fcder und Schwestern. Und sie f\u00fchlen und erleben mit euch mit, w\u00e4hrend ihr euer Leben auf der Erde lebt. Wir sind <em>eine<\/em> gro\u00dfe Familie und wir senden euch unsere Liebe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a9&nbsp;Pamela Kribbe<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbersetzung:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\">Yvonne Mohr<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Pamela channelt Jeshua Liebe Menschen, ich bin Jeshua und ich verbinde mich mit euch aus dem Herzen des Christus-Bewusstseins.Das Christus-Bewusstsein ist ein Energie-Feld, es ist eine Einheit, zu der ihr alle geh\u00f6rt &#8211; ganz gleich, ob euch dies bewusst ist oder nicht. Wir alle sind durch ein pulsierendes Herz, einen Atemzug verbunden, der die&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/der-moment-der-wahl\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-592","post","type-post","status-publish","format-standard","hentry","category-am-morgen-mit-jeshua"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=592"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/592\/revisions"}],"predecessor-version":[{"id":593,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/592\/revisions\/593"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}