{"id":600,"date":"2021-06-02T09:42:55","date_gmt":"2021-06-02T09:42:55","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=600"},"modified":"2021-06-02T09:42:55","modified_gmt":"2021-06-02T09:42:55","slug":"deine-eigene-quelle-der-weisheit","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/deine-eigene-quelle-der-weisheit\/","title":{"rendered":"Deine eigene Quelle der Weisheit"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Jeshua, gechannelt durch Pamela Kribbe<\/strong><\/em><br><br>Liebe Menschen,<br><br>Ich bin Jeshua. Ich bin euer Bruder und Gleichgesinnter. Ich bin hier mitten unter euch. F\u00fchlt mich in eurem Herzen. Ich bin einer von euch. Damit meine ich, dass ich nicht anders bin. Ich bin Mensch gewesen und kannte die Gef\u00fchlstiefen und \u2013h\u00f6hen, die ihr alle in eurem menschlichen Dasein erlebt.<br><br>Ihr denkt oft, dass ein heiliger oder aufgekl\u00e4rter, erleuchteter Geist sich von den emotionalen H\u00f6hen und Tiefen gel\u00f6st habe, durch die ihr geht, das ist jedoch nicht der Fall. Der weise oder der erleuchtete Geist hat das Bewusstsein f\u00fcr die totale Hingabe an das Leben, er widersetzt sich nicht den Wellen und Gem\u00fctsbewegungen im eigenen Herzen. Der erleuchtete, aufgekl\u00e4rte Geist ist frei und haftet nicht irgendeinem bestimmten Gem\u00fctszustand an. Dieses Bewusstsein wogt mit dem menschlichen Sein in all seinen Facetten mit, und in dieser Hingabe steckt die absolute Freiheit, durch die ein aufgekl\u00e4rter Geist Frieden inmitten chaotischer Situationen erfahren kann.<br><br>Was euch als Menschen am meisten Schwierigkeiten macht, am meisten blockiert, ist der Widerstand gegen das Leben: \u2018Nein\u2018 zu dem zu sagen, was sich euch im Heute, in eurem allt\u00e4glichen Leben zeigt, und eure Situation verbessern zu wollen oder unterdr\u00fccken zu wollen, was ihr in euch selbst als schlecht empfindet. Es gibt eine Art Ego in euch, das denkt, es besser zu wissen, und das oft gen\u00e4hrt wird von allerlei Regeln von au\u00dfen, bei denen es h\u00e4ufig um Gut und B\u00f6se geht, darum, was sich geh\u00f6rt und was nicht, wie die Dinge sein sollten, wie Ihr dazu geh\u00f6rt und was euch von anderen Menschen trennt. All diese sozialen und moralischen Regeln bewirken, dass ihr aus diesem Ego heraus versucht, euer Leben zu beherrschen, das nat\u00fcrliche Leben, wie es sich euch spontan zeigt. Diesen Kampf verliert ihr; diesen Kampf verliert ihr ganz entschieden. Ihr k\u00f6nnt den Kampf gegen eure eigene Natur, gegen das Leben selbst, lange aufrechterhalten, und ihr k\u00f6nnt euch selbst mit allerlei spirituellen Theorien dar\u00fcber f\u00fcttern, aber letztendlich verbirgt sich die wahre Freiheit darin, euch ganz und gar dem Leben in euch selbst anzuvertrauen.<br><br>Was genau hei\u00dft das? Beginne im JETZT. F\u00fchle dich selbst. Werde dir in diesem Moment deiner selbst bewusst und beginne damit mit deinem K\u00f6rper. Dein K\u00f6rper ist Energie, er ist ein energetisches Feld. Er ist nicht etwas au\u00dferhalb von dir; er ist kein Objekt, kein Ding und kein Mechanismus. Dein K\u00f6rper ist von innen heraus beseelt, und du hast durch das Ma\u00df, wie sehr du in ihm anwesend oder abwesend bist, Einfluss auf ihn. Wenn dein Kopf mit Regeln, Theorien und Gedanken vollgestopft ist, kannst du oftmals nicht besonders gut in deinem eigenen Energiefeld, in deinem eigenen K\u00f6rper anwesend sein.<br><br>Ich bitte dich nun, dich bewusst in deinen K\u00f6rper hinein zu begeben, mit deiner Aufmerksamkeit in deine Beine zu gehen, deine F\u00fc\u00dfe auf dem Boden zu sp\u00fcren und deine Gedanken zur Ruhe kommen zu lassen. Es steckt eine gro\u00dfe Weisheit im K\u00f6rper, an der ihr oftmals vorbeigeht, weil es in eurem Kopf zu gesch\u00e4ftig ist. Lasse den K\u00f6rper nun sprechen. Werde dir deines R\u00fcckens und deines R\u00fcckgrats bewusst. Stelle dir vor, dass sich in deinem R\u00fcckgrat ein Licht-Kanal befindet, der das unterste Energiezentrum oder Chakra bei deinem Stei\u00df mit dem Kronenchakra verbindet, dem am h\u00f6chsten gelegenen Zentrum in deinem Energiefeld. Werde dir der Energie-Str\u00f6mung bewusst, die durch dich hindurch l\u00e4uft, durch deinen K\u00f6rper und dein R\u00fcckgrat hindurch, und f\u00fchle, dass du durch diesen Kanal sowohl mit dem Himmel als auch der Erde verbunden bist.<br><br>Unter dir ist die Erde, und die Erde ist ebenfalls kein Ding oder Mechanismus oder Objekt. Sie ist eine lebendige Seele, ein lebendiges Bewusstsein. F\u00fchle, wie du in diesem Bewusstsein ruhst, dadurch, dass du Mensch bist und Teil der Erde bist. Die Erde verf\u00fcgt \u00fcber eine Intelligenz, die alt und weise ist. Werde dir in diesem Moment ganz und gar der Energie der Erde unter dir bewusst und lasse sie in deine F\u00fc\u00dfe str\u00f6men, in deine Beine und in das Stei\u00dfchakra. Nimm bewusst Kontakt mit der Erde auf. F\u00fchle ihre tragende Kraft und bitte sie um eine Botschaft. Was will sie dir sagen? Was ist f\u00fcr dich jetzt wichtig? Lasse ihre Energie durch dich hindurch str\u00f6men, \u00f6ffne dich ihr und schaue, was dann geschieht. F\u00fchle den Raum, den dir das gibt, denn Erd-Energie bringt dich zu dir selbst zur\u00fcck, zu deinen eigenen Wurzeln, in dein eigenes Zentrum, wodurch du ruhig und gelassen die Situationen in deinem Leben betrachten kannst. Die Erde m\u00f6chte dir helfen und dir eine Unterst\u00fctzung sein.<br><br>Nimm jetzt Kontakt mit dem h\u00f6heren Teil des Kanals in deinem R\u00fccken auf, oben in deinem R\u00fcckgrat. Vom Herzen aus und h\u00f6her str\u00f6mt eine Energie, die dich mit der Luft und mit dem Himmel verbindet &#8211; mit kosmischen Energien, die ebenso zu dir geh\u00f6ren wie die Energie der Erde. Deine Seele hat viele Welten bereist. Die Erde ist <em>ein<\/em> m\u00f6glicher Aufenthaltsort oder Wohnsitz. Du tr\u00e4gst in dir ein Wissen und eine Weisheit, die an vielen verschiedenen Orten im Universum entstanden sind. F\u00fchle nun dein eigenes Alter und lasse all diese Wissens-Quellen in dein Bewusstsein vordringen. Nimm Kontakt mit dem Sternenlicht auf, das dir so vertraut ist. Frage dich nicht, woher es kommt; lasse dich einfach darauf ein. F\u00fchle, wie es dich unterst\u00fctzen und dir dienen m\u00f6chte, und wie es sich durch dich mit der Erde verbinden m\u00f6chte. Bitte dieses kosmische Feld auch um eine Botschaft oder um eine Antwort auf eine Frage, die du hast. Diese Antwort oder Botschaft muss nicht in Worten erscheinen, es kann auch sein, dass dir etwas durch ein Gef\u00fchl oder eine Stimmung oder Atmosph\u00e4re mitgeteilt oder verdeutlicht wird.<br><br>Auf diese Weise, durch die Kontaktaufnahme mit den Energien sowohl der Erde als auch des Himmels, m\u00f6chte ich dir eine Intelligenz und eine Weisheit bewusst machen, die nicht aus dem Kopf oder dem Denken hervorgehen, die nicht auf Regeln oder Normen von Gut und B\u00f6se basieren, die oft aus Angst oder einem Bedarf an Kontrolle herr\u00fchren. Es gibt eine gr\u00f6\u00dfere Weisheit in dir und um dich herum, die dich tr\u00e4gt und dir Botschaften \u00fcbermittelt, wenn du dich traust, dich dem hinzugeben und deinen Kopf einmal ausschaltest. In dem Moment, wo du in deinem Leben tiefe Emotionen erlebst, sei es nun Verzweiflung, Angst, \u00c4rger oder einfach Freude, Erf\u00fcllung und Inspiration, liegt die Kunst darin, mit den Wellen dieser Gef\u00fchle mitzugehen und zugleich den Kontakt mit den Quellen der Weisheit aufrecht zu erhalten, die dir zur Verf\u00fcgung stehen. Es ist wichtig, dich nicht gegen das Leben zu wehren, sondern das Leben so wie es sich dir pr\u00e4sentiert mit kosmischer Intelligenz und irdischer Weisheit zu durchdringen und durchtr\u00e4nken.<br><br>Dies wirkt sich transformierend aus. Dies ist der Auftrag, die Berufung. Das Leben zur G\u00e4nze zu erleben und mit Bewusstsein zu umgeben. Dein Bewusstsein ist gr\u00f6\u00dfer als du denkst. Du hast dich durch die Einfl\u00fcsse von au\u00dfen klein machen lassen, die bereits von deiner Geburt an und auch in vorherigen Leben auf dich eingewirkt haben. Dadurch untersch\u00e4tzt du kontinuierlich deine innerliche Weisheit und Kraft.<br><br>Darum sage ich ausdr\u00fccklich: \u201eIch bin einer von euch.\u201c Ich stehe nicht \u00fcber euch, ich bin nicht wesentlich anders. Wir geh\u00f6ren zusammen. Werde dir deiner eigenen Kraft bewusst. Glaube an deine eigene Weisheit und dein Licht und alles wird anders werden. Das Leben ist dann kein Feind mehr, der besiegt werden muss, sondern wird zu einem Gef\u00e4hrten, der dich auf viele Wege mitnimmt. Diese Wege sind mal sch\u00f6n, mal weniger sch\u00f6n, manchmal sehr schmerzhaft, aber du vertraust dem Leben, du vertraust diesem Kameraden. Du ruhst in deiner eigenen Tiefe, deiner eigenen Weisheit. Das macht dich frei, das bringt dich dorthin, wo du sein m\u00f6chtest.<br><br>Ich bin tief mit euch allen verbunden. Wir bilden eine Einheit.<br><br><strong>\u00a9 Pamela Kribbe<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbersetzung:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\">Yvonne Mohr<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Jeshua, gechannelt durch Pamela Kribbe Liebe Menschen, Ich bin Jeshua. Ich bin euer Bruder und Gleichgesinnter. Ich bin hier mitten unter euch. F\u00fchlt mich in eurem Herzen. Ich bin einer von euch. Damit meine ich, dass ich nicht anders bin. Ich bin Mensch gewesen und kannte die Gef\u00fchlstiefen und \u2013h\u00f6hen, die ihr alle in&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/deine-eigene-quelle-der-weisheit\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-600","post","type-post","status-publish","format-standard","hentry","category-am-morgen-mit-jeshua"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=600"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/600\/revisions"}],"predecessor-version":[{"id":601,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/600\/revisions\/601"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}