{"id":602,"date":"2021-06-02T09:47:45","date_gmt":"2021-06-02T09:47:45","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=602"},"modified":"2021-06-02T09:47:45","modified_gmt":"2021-06-02T09:47:45","slug":"deine-ankunft-auf-der-neuen-erde","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/deine-ankunft-auf-der-neuen-erde\/","title":{"rendered":"Deine Ankunft auf der Neuen Erde"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Jeshua, gechannelt durch Pamela Kribbe<\/strong><\/em><br><br>Liebe Freunde,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ich bin hier, ich bin Jeshua.&nbsp;Ich bin euer Bruder.&nbsp;Ich bin euch jetzt so nahe.&nbsp;Und mit &#8222;jetzt&#8220; meine ich nicht nur in diesem Moment, sondern in dieser Epoche, in diesem Zeitalter.&nbsp;Ihr habt euch alle so sehr ver\u00e4ndert.&nbsp;Ich kenne viele von euch schon seit Ewigkeiten.&nbsp;Wir waren schon fr\u00fcher zusammen.&nbsp;In der Zeit, als ich auf der Erde lebte, bin ich vielen von euch begegnet.&nbsp;Und w\u00e4hrend der Jahrhunderte direkt nachdem ich gelebt hatte, f\u00fchlten sich viele von euch davon angezogen, auf der Erde zu inkarnieren.&nbsp;Ihr habt eine \u00d6ffnung im kollektiven Bewusstsein der Menschen wahrgenommen.&nbsp;Ihr wolltet zu dieser \u00d6ffnung, zum Erwachen des Bewusstseins beitragen.&nbsp;Zu dieser Zeit wurde ein neues Bewusstsein ges\u00e4t.&nbsp;Wie ihr wisst, stie\u00df es auf sehr viel Widerstand.&nbsp;Ihr Alle habt diesen Widerstand in eurem eigenen Leben, in diesem Leben und ebenso auch in fr\u00fcheren Leben, erlebt.&nbsp;Ihr habt erlebt, wie es sich anf\u00fchlt, anders zu sein als andere Menschen und ihr habt euch einsam deswegen gef\u00fchlt.&nbsp;Ihr seid die Vorboten, die Pioniere eines neuen Bewusstseins.&nbsp;In dieser Zeit, in diesem Zeitalter findet \u00fcberall auf der Welt eine \u00d6ffnung im menschlichen Bewusstsein statt.&nbsp;Ich bin hier, um dies mit euch zu feiern.&nbsp;Es wird tats\u00e4chlich gerade jetzt eine neue \u00c4ra geboren.&nbsp;Vielleicht empfindet ihr es nicht immer so, weil ihr manchmal unruhig seid.&nbsp;Aber ich kann sehr deutlich das Erwachen in euren Seelen sehen.&nbsp;Ich bin hier, um euch achtungsvoll zu begr\u00fc\u00dfen und euch aus tiefstem Herzen zu ehren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meine liebe Schwester Maria Magdalena ist jetzt hier bei mir, ebenso wie andere gleichgesinnte Seelen.&nbsp;&nbsp;&nbsp;<br>[<em>Manche Menschen im Raum beginnen zu weinen<\/em>]<br>Es ist sch\u00f6n eure Tr\u00e4nen zu sehen.&nbsp;Sie sind ein Zeichen eurer Verbundenheit mit uns.&nbsp;Wir sind hier, um mit euch zu feiern.&nbsp;Was wir zu dieser Zeit am liebsten tun w\u00fcrden, ist eure F\u00fc\u00dfe zu waschen, vor euren F\u00fc\u00dfen niederzuknien und sie zu waschen.&nbsp;Es ist eine Geste unseres Respekts und unserer Verehrung f\u00fcr euch.&nbsp;Wir wollen nicht, dass ihr zu uns als Meister aufschaut.&nbsp;Wir sind eure Freunde, euer Bruder und eure Schwester.&nbsp;Und so laden wir euch ein, mit uns gl\u00fccklich zu sein, denn die neue \u00c4ra hat wirklich begonnen.&nbsp;Wir wissen, dass ihr euch noch immer von den Belastungen der Vergangenheit und der Zukunft geplagt f\u00fchlt.&nbsp;Aber wir laden euch ein, diese Belastungen noch einmal zu betrachten.&nbsp;Weil ihr durch die Tiefe der Angst, des Kummers und der Traurigkeit gegangen seid, weil ihr sie durchlebt habt, gibt es in eurem Herzen nun einen Raum f\u00fcr Mitgef\u00fchl.&nbsp;Wahres Mitgef\u00fchl f\u00fcr euch selbst und Andere.&nbsp;Das ist es, worum es beim Christus-Bewusstsein geht.&nbsp;Darum, wirklich und ohne Urteil zu verstehen, was eine andere Person durchmacht;&nbsp;einfach mit dieser anderen Person von Seele zu Seele beisammen zu sein.&nbsp;Darum geht es bei der Christus-Saat und dem Christus-Bewusstsein.&nbsp;Ihr seid jetzt da.&nbsp;Ihr m\u00fcsst nicht so hart an euch arbeiten oder denken, dass ihr euch verbessern m\u00fcsstet.&nbsp;Wir w\u00fcnschten, ihr k\u00f6nntet es aus unserem Blickwinkel heraus sehen: dass ihr vollkommen seid so wie ihr seid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber wir erkennen, dass ihr in eurem t\u00e4glichen Leben immer noch mit schmerzhaften Emotionen k\u00e4mpft.&nbsp;Wir bitten euch daher nun, in einer kleinen Fantasie-\u00dcbung mit uns zu reisen.&nbsp;Stellt euch vor, ihr steht vor einem Torfl\u00fcgel.&nbsp;Die T\u00fcr ist bereits offen und ihr steht auf der Schwelle zur Neuen Erde.&nbsp;Ihr k\u00f6nnt bereits die Energie dieser neuen Erde, den Frieden und die Harmonie sp\u00fcren.&nbsp;Und ihr k\u00f6nnt die Sch\u00f6nheit der Natur sehen.&nbsp;Es sieht vielleicht ein bisschen aus wie das Land, in dem wir uns jetzt befinden [<em>in S\u00fcdfrankreich, auf einem H\u00fcgel<\/em>], weil die Sch\u00f6nheit und Wildheit der Natur hier der Energie der Neuen Erde \u00e4hneln.&nbsp;Und wie ihr hier nahe bei diesem Tor, dieser T\u00fcr steht, haltet ihr die Hand eines Kindes.&nbsp;Ihr bemerkt, wie aufgeregt dieses Kind ist, da es in das neue Land vordringen will, aber ihr k\u00f6nnt auch Angst in seinem oder ihrem K\u00f6rper sp\u00fcren.&nbsp;Es scheint ein gro\u00dfer Schritt zu sein, das Alte zur\u00fcckzulassen und die Neue Erde zu betreten.&nbsp;Das Kind hat immer noch Angst wegen all dem, was ihm von seinen Eltern und von der Gesellschaft erz\u00e4hlt wurde.&nbsp;Er oder sie hat Angst zu vertrauen und den gro\u00dfen Sprung nach vorne zu machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fchlt jetzt die Hand dieses kleinen Jungen oder M\u00e4dchens in der euren.&nbsp;Dieses Kind spiegelt den unruhigen Teil von euch wider, der Angst hat, den n\u00e4chsten Schritt zu machen.&nbsp;Das ist die Trag\u00f6die, die wir mitunter an euch bemerken.&nbsp;Auf der einen Seite sehnt ihr euch so sehr lange danach, nach Hause zu gehen, wieder den Frieden und die Harmonie zu erfahren, die zu euch geh\u00f6ren.&nbsp;Auf der anderen Seite habt ihr Angst, das Alte loszulassen, auch wenn es sehr schmerzhaft ist, daran festzuhalten.&nbsp;Wir bitten euch nun, das Kind zu umarmen und es zu beruhigen.&nbsp;F\u00fchlt, wie es sich in euren Armen entspannt.&nbsp;Jetzt seht, ob es einige Schritte vorw\u00e4rts machen will.&nbsp;Aber beurteilt es nicht, wenn es immer noch Angst hat.&nbsp;Sagt dem Kind, dass ihr in jedem Fall f\u00fcr es da seid und dass ihr sein F\u00fchrer sein werdet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch wenn ihr noch an der Schwelle, nur am Anfang dieses neuen Landes steht, atmet die Energie ein.&nbsp;Ihr kommt jetzt wirklich nach Hause, und&nbsp;<em>Zuhause ist auf der Erde<\/em>.&nbsp;Ihr habt oft gedacht, dass Zuhause woanders sei, dass es irgendwo da oben im Himmel sei, wo ihr herkommt.&nbsp;Aber der Zweck eurer langen Reise viele Lebenszeiten hindurch ist es, den Himmel auf die Erde zu bringen und ihn mit euren Mitmenschen zu teilen.&nbsp;Ihr sollt die Energie des Himmels auf die Erde bringen.&nbsp;In der Vergangenheit musstet ihr euch oft verstecken, weil ihr diese Sehnsucht hattet.&nbsp;Die Zeit des Versteckens ist jetzt vorbei.&nbsp;Eure Anwesenheit wird hier und jetzt gebraucht.&nbsp;Ihr seid noch immer die Wegbereiter, die Pioniere des Bewusstseins.&nbsp;Und wir bitten euch jetzt, in eurer Macht zu stehen und stolz auf euch selbst zu sein.&nbsp;Das hat nichts mit dem Ego zu tun;&nbsp;es geht darum, die Ausstrahlung eurer Seele wirklich zum Ausdruck zu bringen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zudem ermutigen wir euch, als Lichtarbeiter zusammen zu kommen und eure Energien miteinander zu teilen.&nbsp;Es ist jetzt an der Zeit, euch auf eine sehr offene und flexible Art und Weise zu verbinden.&nbsp;Indem ihr euch gegenseitig \u00f6ffnet, beschleunigt ihr euren Heilungsprozess.&nbsp;Gerade in dieser Region S\u00fcdfrankreichs sind die Energien sehr f\u00fcr diesen Heilungsprozess geeignet.&nbsp;Wir laden euch ein, dies f\u00fcr euch selbst zu f\u00fchlen.&nbsp;Sp\u00fcrt die Energie der Erde, wie sie aus dem Land unter euren F\u00fc\u00dfen kommt*.&nbsp;Die Erde ist offen und m\u00f6chte euch empfangen.&nbsp;Sie m\u00f6chte euch unterst\u00fctzen und euch mit allem versorgen, was ihr als Mensch braucht.&nbsp;Auf der materiellen Ebene werdet ihr sehen, dass die Menschen auf der Neuen Erde mit einfachen Mitteln zufriedener sein werden, aber sie werden dies nicht als Mangel erleben, nicht als eine Armut.&nbsp;Sie werden gegen\u00fcber der Erde respektvoller sein und einen Lebensstil haben, der mehr mit der Natur harmoniert.&nbsp;Statt sich mit materiellen Dingen zu ern\u00e4hren, werden sie sich mit spiritueller \u2018Nahrung\u2018 Gen\u00fcge tun.&nbsp;Sie werden sich von den Beziehungen gen\u00e4hrt f\u00fchlen, die sie mit sich selbst, mit der Natur und mit anderen Menschen haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir laden euch ein, in eurem eigenen Leben ein Beispiel f\u00fcr diesen Lebensstil zu sein.&nbsp;Eure Energien mit anderen Lichtarbeitern zu teilen wird euch helfen, beherzt zu bleiben und auf euer Ziel fokussiert zu bleiben.&nbsp;Feiert eure Ankunft auf der Neuen Erde miteinander.&nbsp;Das ist unsere Botschaft f\u00fcr heute.&nbsp;Wir sind voller Hoffnung und Freude f\u00fcr euch.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*A.d.\u00dc:&nbsp; Bitte seid Euch bewusst, dass Ihr dies hier und jetzt tun k\u00f6nnt. \u2018Seid\u2018 in S\u00fcdfrankreich und sp\u00fcrt die Energie des Landes unter Euren F\u00fc\u00dfen&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a9 Pamela Kribbe<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbersetzung:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\">Yvonne Mohr<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Jeshua, gechannelt durch Pamela Kribbe Liebe Freunde, ich bin hier, ich bin Jeshua.&nbsp;Ich bin euer Bruder.&nbsp;Ich bin euch jetzt so nahe.&nbsp;Und mit &#8222;jetzt&#8220; meine ich nicht nur in diesem Moment, sondern in dieser Epoche, in diesem Zeitalter.&nbsp;Ihr habt euch alle so sehr ver\u00e4ndert.&nbsp;Ich kenne viele von euch schon seit Ewigkeiten.&nbsp;Wir waren schon fr\u00fcher zusammen.&nbsp;In&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/deine-ankunft-auf-der-neuen-erde\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-602","post","type-post","status-publish","format-standard","hentry","category-am-morgen-mit-jeshua"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=602"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/602\/revisions"}],"predecessor-version":[{"id":603,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/602\/revisions\/603"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}