{"id":683,"date":"2022-03-14T08:31:01","date_gmt":"2022-03-14T08:31:01","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=683"},"modified":"2022-03-14T08:31:01","modified_gmt":"2022-03-14T08:31:01","slug":"der-kontakt-mit-geistigen-fuehrern","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/der-kontakt-mit-geistigen-fuehrern\/","title":{"rendered":"Der Kontakt mit geistigen F\u00fchrern"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Jeshua, gechannelt durch Pamela Kribbe<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Menschen,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ich bin Jeshua. Ich bin hier. Ich bin f\u00fcr euch da, um eure Hand zu halten und euch mitzunehmen zu dem, wer ihr seid, zu eurer wahren Natur, zu dem, wer und wie ihr urspr\u00fcnglich seid. Nicht das, was aus euch gemacht wurde, in diesem Leben voller Widerspr\u00fcche, voller Anforderungen und Pflichten, die ihr in eurem Leben erf\u00fcllen zu m\u00fcssen meint. Lasst das einmal los, in diesem Moment. Seid einfach, wer ihr seid, ohne Anspr\u00fcche an euch selbst zu stellen, ohne Erwartungen, ohne die ewigen Pflichten, die euch anfallen wie Gei\u00dfeln. Ihr gei\u00dfelt euch oft selbst damit, was ihr aus eurer Sicht alles tun m\u00fcsst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und so auch hier: Heute sind wir hier in einem Workshop, in dem es um die Kontaktaufnahme mit geistigen F\u00fchrern geht, aber dennoch spielt auch das im Wesentlichen keine Rolle. Denn wichtig ist allein, dass ihr euch in euren nat\u00fcrlichen Zustand zur\u00fcckgleiten lassen k\u00f6nnt, und von dort aus wird alles m\u00f6glich. Euch zu Hause f\u00fchlen mit dem, wer ihr seid, euch mit eurem wahren Wesen gl\u00fccklich zu f\u00fchlen, das ist es, wonach ihr sucht!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geistige F\u00fchrer k\u00f6nnen euch dabei helfen, so wie ich euch meine Hand reiche, um euch daran zu erinnern, wer ihr seid: die Licht-Sonne, der Licht-Stern, der aus eurem Herzen strahlt. F\u00fchlt einmal, wer ihr seid. Und dabei geht es nicht um Bilder oder Visionen, sondern darum, anwesend zu sein bei dem, wer ihr seid, von Kopf bis Fu\u00df.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich sehe euch alle.<br>Stellt euch einmal vor, wie ich hier bei euch bin und vor euch stehe. Ihr m\u00fcsst es nicht sehen, ihr k\u00f6nnt es auch f\u00fchlen. Und ich reiche euch etwas. Es ist eine Blume aus Licht. Nehmt sie an, nehmt sie in euer Herz auf. Ich bin hier, um euch zu sagen, dass ihr gut seid. Dass ihr nicht zu ringen und zu k\u00e4mpfen braucht in eurem Leben, dass ihr <em>empfangen, annehmen<\/em> d\u00fcrft, heute und an allen anderen Tagen. Ihr seid ein mutiger Engel, der hierher herabgestiegen ist und auf der Erde Fleisch und Blut geworden ist. Hier versucht, euer Licht wiederzufinden und es auf andere auszustrahlen. Ihr seid alle auf eure eigene Weise Lichtarbeiter: Seelen, die einen brennenden Wunsch in ihrem Herzen tragen, diese Erde mit einem Funken Licht zu versehen, wobei Licht f\u00fcr Liebe, Verst\u00e4ndnis, Verbindung, Vergebung, Gemeinschaft, Linderung von altem Schmerz, Aufl\u00f6sung von Wunden steht. Sp\u00fcrt diese Absicht in eurem Herzen. Dies ist euer Licht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr brauchtet Mut, um diesen Sprung ins Tiefe zu wagen, und ihr seid hier nicht allein. Es steht ein Team von Engeln oder F\u00fchrern um euch herum, die euch ermutigen und euch immer mit einer Verbindung, einem Kanal hin zu dem versorgen, wer ihr wirklich seid, zu eurem Zuhause. Dieses Zuhause ist nicht wirklich irgendwo da oben oder im Jenseits, auf der anderen Seite des Schleiers. Nein, das Zuhause ist hier, es ist <em>jetzt<\/em> in euch anwesend. Es ist in eurem Herzen. Und die geistigen F\u00fchrer haben die Aufgabe, immer wieder an die T\u00fcr eures Herzens zu klopfen, bis ihr es h\u00f6rt und wirklich glaubt und erkennt, dass ihr nicht das Fleisch und Blut seid, aus dem euer K\u00f6rper besteht, sondern dass ihr das lebendige Bewusstsein seid, das diese Form vor\u00fcbergehend gew\u00e4hlt hat, um hier etwas anzusiedeln, etwas von dem unverg\u00e4nglichen Licht auszustrahlen, das ihr seid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sch\u00f6pft Freude daraus! Wie mutig ihr seid! Traut euch, euch selbst das zu sagen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Habt keine Angst davor, auf der Erde zu leben, seid \u00fcberzeugt davon, wer ihr seid. Lebt so, wie ihr leben wollt. Ihr seid nicht hier, um andere nachzuahmen, zu imitieren. Ihr setzt eure <em>eigenen<\/em> Ma\u00dfst\u00e4be. Ihr seid ein Meister in euch selbst. Von der Seite aus, von der ich spreche, der nichtmateriellen oder \u00fcberirdischen Seite, wie ihr sie nennt, von dieser Seite aus wollen wir euch einzig darin best\u00e4tigen, dass ihr selbst Meister \u00fcber euer eigenes Leben seid und dass eine tiefe Kraft in euch schlummert, gerade <em>weil<\/em> ihr inkarniert seid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir auf der anderen Seite k\u00f6nnen euch mit Best\u00e4tigung und Ermutigung versehen, aber ihr habt es auf euch genommen, euer Licht in einer Umgebung am Leuchten zu halten, die in ihrer Schwingung schwer und dicht ist. Erkennt euch selbst daf\u00fcr an. Wenn ihr eure eigene Gr\u00f6\u00dfe anerkennt und eure eigene Sch\u00f6nheit sehen k\u00f6nnt, dann wird es viel einfacher, in eurem Leben die Richtung zu finden, den Weg zu finden, der von Natur aus zu euch geh\u00f6rt. Euer Wunsch nach Kontakt mit F\u00fchrern ist im Wesentlichen der Wunsch, &#8222;zu wissen, wer ihr seid&#8220;, &#8222;euch zu erinnern, wer ihr seid&#8220;, und von dort aus euren Weg zu finden, mit Leichtigkeit, ohne allzu viel nachdenken zu brauchen, ohne so viel k\u00e4mpfen zu m\u00fcssen. Ich respektiere diese Sehnsucht, und darum sage ich: Sucht es zuerst in euch selbst, lasst den Wunsch danach los, dass etwas von au\u00dfen kommt, um euch zu retten, und sinkt tief in eure eigene inkarnierte Gegenwart und Anwesenheit, in euren K\u00f6rper also hinein. F\u00fchlt, wie eure Seele dort jetzt einen Platz gefunden hat, an dem sie sich zum Ausdruck bringt. F\u00fchlt, wie eure Seele in allen Zellen eures K\u00f6rpers pr\u00e4sent ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Eure Seele hat eine Botschaft f\u00fcr euch, hier, in diesem Moment. Eure Seele sagt: &#8222;Ich will leben, ich will ich selbst sein, ich will strahlen, auf meine eigene Weise&#8220;, und <em>lasst<\/em> die Seele strahlen. \u00d6ffnet die Zellen in eurem K\u00f6rper. Stellt euch vor, dass sie euer Licht absorbieren, es in sich aufnehmen und so die \u00dcberf\u00fchrung, den \u00dcbergang von der Seele hin zur Erde schaffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Kontakt mit den F\u00fchrern, nach dem ihr euch sehnt, geht aus einem Heimweh hervor. Einem Heimweh nach Spontaneit\u00e4t, nach Einfachheit und Leichtigkeit, danach, euch frei und spontan auszudr\u00fccken. Kurz und b\u00fcndig, <em>ihr selbst zu sein<\/em>. Fangt hiermit an, indem ihr ganz bei euch, in eurem K\u00f6rper anwesend seid.<br>Begr\u00fc\u00dft euch selbst im Hier und Jetzt, nicht so, wie ihr gerne sein <em>w\u00fcrdet<\/em> oder eurer Ansicht nach sein <em>solltet<\/em>, sondern so, wie ihr hier und jetzt seid &#8211; verletzlich, offen, menschlich, gebrochen vielleicht in mancher Hinsicht, all das darf sein, euer Schmerz darf da sein. Lasst euer Licht leuchten und hei\u00dft euch selbst willkommen in den tiefsten Fasern dessen, wer ihr seid. Seht auch euren Schmerz und eure Trauer an, das Nicht-mehr-Wissen, die Ungewissheit, Unsicherheit, das Fehlen Vertrauen vielleicht. Seid euer eigener F\u00fchrer, erbarmt euch der gepeinigten Teile in euch, legt eure Engelsfl\u00fcgel um sie, seid sanft zu euch selbst. Habt Erbarmen. Ihr seid so streng mit euch selbst, habt Erbarmen und lasst das Licht str\u00f6men, durch eure K\u00f6pfe, eure Schultern, euer Herz, euren Bauch, eure Oberschenkel, eure Knie, eure Waden, eure Kn\u00f6chel und F\u00fc\u00dfe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Meine lieben Br\u00fcder und Schwestern, ich kenne und erkenne euch. Ich wei\u00df, wer ihr seid. Ich bin in euren Schuhen gegangen. Auch ich war inkarniert, und der Kampf, den ihr innerlich durchmacht, ist mir ein Begriff, die \u00e4ngstlichen Gedanken, die Zweifel, und ich sage euch, eines wei\u00df ich: Die L\u00f6sung ist nicht, dass ihr die \u00c4ngste und die Zweifel bek\u00e4mpft, dass ihr euch in den Kampf gegen sie begebt. Die wahre Kraft der Christusenergie, f\u00fcr die ich <em>ein<\/em> Repr\u00e4sentant war &#8211; deren wahre Kraft darin besteht, dass ihr all das in euch selbst annehmt, und es so auch in einem anderen anerkennen und vergeben k\u00f6nnt -, die wirkliche Kraft und Absicht der Christusenergie ist Einheit, Einheit zu finden. Und das beginnt in euch selbst, indem ihr euch vollst\u00e4ndig so annehmt, wie ihr <em>jetzt<\/em> seid, mit allen dunklen Flecken, \u00c4ngsten und Zweifeln, die damit einhergehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fchlt, wie diese Energie jetzt hier im Raum anwesend ist. F\u00fchlt, wie sie euch sanft macht. Ihr wollt zu euch selbst nach Hause kommen. Ich, die Lehrer auf der anderen Seite, eure F\u00fchrer, sind wie Hebammen, die euch bei eurer Geburt ins Licht helfen. Es ist keine Kunst, ins Licht geboren zu werden, wenn ihr euch in einer Lichtsph\u00e4re befindet wie auf unserer Seite, wo ihr st\u00e4ndig mit Botschaften der Anerkennung und der Liebe versorgt werdet, wo ihr von Sch\u00f6nheit und einer verfeinerten Schwingung umgeben seid. Nein, es ist eure <em>wahre<\/em> Kraft, dass ihr auf der <em>Erde<\/em> euer eigenes Licht erkennt, inmitten einer Umgebung, die es nicht immer widerspiegelt. <em>Dort, damit<\/em> seid ihr Lichttr\u00e4ger und Pioniere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Meine heutige Botschaft ist: Erinnert euch, wer ihr seid. Das ist die Botschaft eurer F\u00fchrer, die euch umgeben.<br>Entspannt euch, liebt euch selbst, und ganz von selbst werdet ihr dann einen neuen Fluss in eurem Leben begr\u00fc\u00dfen k\u00f6nnen. Wenn ihr euch selbst lieben k\u00f6nnt, wird euer Denken von selbst weniger gesch\u00e4ftig und angespannt, ihr lasst einfach ein bisschen mehr los, ihr lebt mehr in Hingabe. Ihr wisst, dass das Universum das Beste f\u00fcr euch will, dass vor euch ein Lebensweg entworfen daliegt, dass ihr nicht hart daf\u00fcr arbeiten m\u00fcsst. Und Botschaften, geistige, spirituelle Botschaften, wie ihr sie von F\u00fchrern erwarten k\u00f6nnt, umgeben euch \u00fcberall, von allen Seiten. Das Universum oder Gott oder wie auch immer ihr es nennen wollt, spricht zu euch auf vielerlei Arten und gibt euch subtile Signale. Es kann durch eure innere Welt stattfinden, in der ihr eine helfende Energie erfahrt, aber es kann auch in Form eines anderen Menschen sein, der genau im richtigen Moment euren Weg kreuzt, es kann sein in Form eines Tieres, das euren Weg kreuzt, eines Buches, eines Musikst\u00fcckes. Die kleinsten Dinge k\u00f6nnen die Sprache der Seele sein, wenn ihr ein Auge daf\u00fcr habt. Und wann habt ihr daf\u00fcr ein Auge? Wenn ihr euch innerlich in einem Raum des Vertrauens und der Selbstannahme befindet. Des Wissens, dass ihr sch\u00f6n seid und das Beste verdient.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noch einmal sage ich euch: Ich reiche euch meine Hand, wir sind eins, verbunden in demselben Wunsch. Glaubt an dieses Licht, das die Erde jetzt ber\u00fchrt. Das Feld der Christusenergie, von dem einen Samen auf der Erde zu pflanzen ich einst kam, bl\u00fcht jetzt auf. Viele Menschen sehnen sich danach, aus dem Herzen zu leben, aus dem Licht ihrer Seele zu leben, und ihr <em>geh\u00f6rt<\/em> zu dieser Gruppe von Menschen. Schon seit vielen Jahrhunderten tragt auch ihr diesen Samen mit euch und wollt ihr ihn auf der Erde aufkeimen lassen. Jetzt ist die Zeit gekommen, in der diese Sehnsucht weiter gefasst ist als je zuvor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich preise euch f\u00fcr euren Mut, wiederum hier auf der Erde zu sein und dem alten Traum von einer neuen Erde Gestalt zu geben, in dem die Menschen in Frieden und Verbundenheit miteinander leben. Das sind gro\u00dfe Worte, aber jeder von euch tragt ihr in eurem Leben St\u00fcck f\u00fcr St\u00fcck dazu bei. Und daf\u00fcr danke ich euch, tief und von Herzen. Bitte nehmt meinen Dank an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a9&nbsp;Pamela Kribbe<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbersetzung:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\">Yvonne Mohr<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Jeshua, gechannelt durch Pamela Kribbe Liebe Menschen, ich bin Jeshua. Ich bin hier. Ich bin f\u00fcr euch da, um eure Hand zu halten und euch mitzunehmen zu dem, wer ihr seid, zu eurer wahren Natur, zu dem, wer und wie ihr urspr\u00fcnglich seid. Nicht das, was aus euch gemacht wurde, in diesem Leben voller&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/der-kontakt-mit-geistigen-fuehrern\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-683","post","type-post","status-publish","format-standard","hentry","category-am-morgen-mit-jeshua"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/683\/revisions"}],"predecessor-version":[{"id":684,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/683\/revisions\/684"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}