{"id":717,"date":"2022-07-08T13:05:53","date_gmt":"2022-07-08T13:05:53","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=717"},"modified":"2022-07-08T13:05:53","modified_gmt":"2022-07-08T13:05:53","slug":"fuelle-liegt-im-innern","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/die-erde\/fuelle-liegt-im-innern\/","title":{"rendered":"F\u00fclle liegt im Innern"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Die Erde, gechannelt durch Pamela Kribbe<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Freunde,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ich bin Mutter Erde. Ich bin gl\u00fccklich, mich heute mit euch zu verbinden. Ich bin der Geist [spirit], der in eurem Planeten wohnt, der die gesamte Natur und damit auch euch und eure K\u00f6rper durchdringt. Bitte werdet euch meiner Energie, der Erdenenergie in eurem eigenen K\u00f6rper bewusst und erkennt, dass euer K\u00f6rper einen nat\u00fcrlichen Rhythmus und eine nat\u00fcrliche Weisheit hat. Wenn ihr die Antworten auf die Fragen eures Lebens erkennen m\u00f6chtet, bitte seid euch bewusst, dass ihr sie nicht wirklich empfangen k\u00f6nnt, ohne euch mit eurem K\u00f6rper zu verbinden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entspannt euren K\u00f6rper darum jetzt einmal. Seid euch eurer H\u00e4nde, eurer F\u00fc\u00dfe und der Art und Weise bewusst, wie ihr atmet, und seid euch bewusst, dass euer K\u00f6rper viele Emotionen speichert, auch wenn ihr euch ihrer nicht gewahr seid. Je entspannter ihr seid, desto mehr verborgene Emotionen k\u00f6nnen an die Oberfl\u00e4che kommen. Oft verbirgt euer Denken diese Gef\u00fchle hinter verschlossenen T\u00fcren. Aus meinem Blickwinkel, dem Blickwinkel der Natur, betrachtet, seid ihr allzu viel in euren K\u00f6pfen. Das ist nicht nat\u00fcrlich. Stellt euch darum nun vor, dass euer Bewusstsein hinunter steigt, dass es ganz sanft, wie eine Brise, in eure Kehle und eure Brust hinunter geht. Sagt Hallo zu eurem K\u00f6rper und geht mit eurem Bewusstsein in euren Bauchraum, euren Bauch und weiter hinunter in eure Beine, eure Knie und eure F\u00fc\u00dfe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erinnert euch, dass ihr ein Teil der Natur seid, dass ihr Gesch\u00f6pfe der Erde seid. Euch durchstr\u00f6mt eine Lebensstr\u00f6mung, die vom Verstand nicht kontrolliert werden kann. Diese nat\u00fcrliche Str\u00f6mung des Lebens, auf die euer K\u00f6rper so gut eingestimmt ist, ist im Einklang mit eurer Seele. Die Seele und der K\u00f6rper sind eng miteinander befreundet. Euer Verstand und eure Beurteilungen beeintr\u00e4chtigen dies oft. Ich lade euch daher ein, Themen wie Arbeit und F\u00fclle von der Ebene eures <em>K\u00f6rpers<\/em> und eurer <em>Seele<\/em> aus zu erkunden:<br>Stellt euch daf\u00fcr nun einmal vor, ihr geht hinaus in die Natur und wandert in einer wundervollen Landschaft. Eure F\u00fc\u00dfe sind nackt und ihr k\u00f6nnt die Erde darunter sp\u00fcren. Ihr f\u00fchlt den Sonnenschein auf eurer Haut und h\u00f6rt die Ger\u00e4usche der Natur. Ihr f\u00fchlt, dass ihr euch in keinster Weise behaupten oder beweisen m\u00fcsst. Ihr k\u00f6nnt euch wirklich entspannen.<br>Richtet dann euren Fokus auf das Licht der Sonne. F\u00fchlt, dass die Sonne ebenso eine innere Dimension hat wie auch die Erde. F\u00fchlt den Sonnenschein in eurem Herzen. Er weckt euch auf und erinnert euch an die F\u00fclle, die in eurem eigenen Herzen anwesend ist. Erinnert euch wie es ist, fr\u00f6hlich, sorglos und verspielt zu sein. Es \u00e4hnelt dem, wie die Natur, die Tiere, die Pflanzen und die Blumen f\u00fchlen. Sie kennen weder die Energie der Sorge noch die Energie des Urteilens. Sie sind sehr pr\u00e4sent im Jetzt. Und dies ist ein wichtiger Teil der F\u00fclle: unbeschwert, unbek\u00fcmmert, fr\u00f6hlich und sorglos sein.<br>Bitte bedenkt, dass wahre F\u00fclle eine <em>innere<\/em> Qualit\u00e4t ist, nicht etwas au\u00dferhalb von euch. Ihr k\u00f6nnt das ganze Geld der Welt und eine Menge materieller G\u00fcter haben, aber wenn ihr weiterhin in eurem Verstand eingeschlossen seid und euch viel sorgt, dann werdet ihr es nicht genie\u00dfen. Echte F\u00fclle liegt im Innern. Ihr k\u00f6nnt sie jetzt euch selbst geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Erste ist dabei, euch nicht in euren eigenen Tr\u00e4umen zu beschr\u00e4nken. Fragt euch auf unbek\u00fcmmerte Weise: \u201eWas schenkt mir am meisten Freude im Leben? Was l\u00e4sst mich aufgeregt, gl\u00fccklich sein, fast wie ein Kind es sein kann?\u201c. Lasst diese Energie der Freude durch euren K\u00f6rper flie\u00dfen und erkennt, dass dies eure wahre Bestimmung ist: diese Energie der Freude zu finden. Genau das ist wahre F\u00fclle. Ihr k\u00f6nnt diese Freude nur finden und euch erlauben, sie zu haben, wenn ihr wirklich an euch selbst glaubt: &#8222;Ich darf all das haben, ich darf mich so f\u00fchlen.&#8220; K\u00f6nnt ihr sp\u00fcren, wie weit entfernt diese Vorstellung von eurem gewohnten Denken entfernt ist?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es stimmt mich traurig zu sehen, wie viele von euch das Gef\u00fchl haben, nicht wirklich gut genug zu sein und so hart arbeiten und ihr Bestes geben zu m\u00fcssen, um es wert zu sein.<br>Schaut euch selbst an und schaut, ob ihr in euch die Stimme finden k\u00f6nnt, die euch vorschreibt, dass ihr gut sein m\u00fcsst, schwer arbeiten m\u00fcsst, etwas leisten m\u00fcsst. Bitte erkennt, dass dies nicht die Stimme der Natur, nicht die Stimme eurer Seele ist. Es ist die Stimme der Gesellschaft und der Tradition.<br>Deshalb ist es oft schwierig, eine Arbeit zu finden, die <em>wirklich<\/em> mit euch resoniert. Es verlangt von euch, euch von der Gesellschaft und von vielen Standards der Gesellschaft zu l\u00f6sen. Die Gesellschaft wird zu euch sagen: &#8222;Das kannst du nicht machen, du kannst nicht wieder wie ein Kind sein, du musst erwachsen werden, du kannst nicht so ein Tr\u00e4umer sein&#8220;. Sp\u00fcrt ihr, wie traurig das ist und wie sehr es dem Rhythmus der Natur widerspricht? Ich bitte euch daher, dies zu \u00e4ndern und eine neue Energie in die Gesellschaft zu tragen, indem ihr anders seid und auf die Stimme eures Herzens h\u00f6rt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr k\u00f6nnt dies in eurem t\u00e4glichen Leben tun, indem ihr die Dinge umdreht und weniger fragt: &#8222;Was erwartet die Gesellschaft von mir?&#8220; und &#8222;Was wollen andere Menschen von mir?&#8220;, sondern indem ihr euch fragt: &#8222;Was will <em>ich<\/em>, was macht <em>mir<\/em> wirklich Freude?&#8220;. Auf den ersten Blick denkt ihr vielleicht: &#8222;Das ist doch egoistisch! Kann ich mich nur auf mich konzentrieren und darauf was ich mag?!&#8220; Doch dann versteht ihr noch nicht. Die Wahrheit ist, dass wenn ihr auf die Freude eures Herzens h\u00f6rt, ihr andere Menschen damit begl\u00fcckt und segnet. Ihr werdet anderen Menschen ein Beispiel, ein Vorbild sein. Sie m\u00f6gen \u00e4ngstlich reagieren, wenn sie jemanden sehen, der es liebt, sich loszurei\u00dfen, sich zu befreien und seinem oder ihrem eigenen Weg zu folgen, doch am Ende ist es die Aufgabe und Mission jedes Menschen, die Stimme seines eigenen Herzens zu finden. Darum vertraut der Sprache eures K\u00f6rpers und euren Emotionen, vertraut der Stimme der Freude.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a9&nbsp;Pamela Kribbe<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbersetzung:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\">Yvonne Mohr<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Erde, gechannelt durch Pamela Kribbe Liebe Freunde, ich bin Mutter Erde. Ich bin gl\u00fccklich, mich heute mit euch zu verbinden. Ich bin der Geist [spirit], der in eurem Planeten wohnt, der die gesamte Natur und damit auch euch und eure K\u00f6rper durchdringt. Bitte werdet euch meiner Energie, der Erdenenergie in eurem eigenen K\u00f6rper&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/die-erde\/fuelle-liegt-im-innern\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-717","post","type-post","status-publish","format-standard","hentry","category-die-erde"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=717"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/717\/revisions"}],"predecessor-version":[{"id":718,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/717\/revisions\/718"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}