{"id":743,"date":"2022-08-05T08:30:28","date_gmt":"2022-08-05T08:30:28","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=743"},"modified":"2022-08-05T08:30:28","modified_gmt":"2022-08-05T08:30:28","slug":"folgt-dem-ruf-eurer-seele","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/folgt-dem-ruf-eurer-seele\/","title":{"rendered":"Folgt dem Ruf Eurer Seele"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Pamela channelt Jeshua<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Menschen,<br><br>ich bin Jeshua. Ich bin hier als ein Bruder und ein Lehrer. Ich bin mit euch verbunden und ich wei\u00df nur allzu gut, wie tief menschliche Emotionen sich anf\u00fchlen und wie sie euch von eurem Kern, von eurer Seele entfernen k\u00f6nnen. Ich bin selbst Mensch gewesen und habe in den Extremen von Schmerz und Verlassenheit nach einer \u00d6ffnung, nach Licht gesucht und wei\u00df, wie es sich anf\u00fchlt, zwischen den Extremen von Licht und Dunkel, Liebe und Angst zu leben.<br><br>Ich bitte euch zuallererst um Mitgef\u00fchl f\u00fcr euch selbst \u2013 wo auch immer ihr euch in eurem Leben gerade befindet, habt Erbarmen mit euch selbst. Erkennt, dass ihr euer absolut Bestes tut und dass in eurem Leben oft Kr\u00e4fte und Gesetzm\u00e4\u00dfigkeiten am Werke sind, die ihr nicht mit eurem Verstand \u00fcberblicken oder mit eurem Willen beherrschen k\u00f6nnt. Es gibt eine gr\u00f6\u00dfere Dynamik, die euer Leben tr\u00e4gt wie die Wellen des Meeres, die mitunter so hoch und rau sind, dass ihr, wenn ihr mitten darin schwimmt, nicht begreift, wohin es geht, denn ihr k\u00f6nnt es nicht von oben \u00fcberblicken.<br><br>Dennoch stecken im Wasser selbst &#8211; und im Wasser des Meeres -, eine Kraft und eine Weisheit, die Bedeutung und Tiefe haben.<br>Stellt euch jetzt einmal vor, dass ihr auf dem Meer im Wasser treibt, dass die See st\u00fcrmisch ist und unerwartete Bewegungen macht. Versucht dennoch, euch zu entspannen und dem Wasser zu vertrauen. Stellt euch vor, dass ihr eure Muskeln lockert und entspannt, jetzt, in diesem Moment, und f\u00fchlt, wie die Erde euch hilft. Euer K\u00f6rper geht aus der Erde hervor und die nat\u00fcrliche Str\u00f6mung der Erde hilft euch, euch zu entspannen.<br><br>Atmet ruhig zu eurem Bauch hin. Stellt euch vor, dass ihr im Wasser liegt und euch einfach nur auf den <em>jetzigen<\/em> Moment konzentriert. Ihr m\u00fcsst nichts \u00fcberblicken, ihr m\u00fcsst es nicht begreifen, ihr f\u00fchlt einfach die Kraft des Wassers. Nun nehmt ihr auch eine Energie in dem Wasser, in der See wahr. Lasst sie zu euch vordringen, in der See ist Weisheit. Euer pers\u00f6nliches Ich, das gewohnt ist, das Leben steuern und beherrschen zu wollen, f\u00fcrchtet sich oft vor dieser Weisheit. Es traut sich nicht, sich ihr anzuvertrauen. Aber wenn ihr mit der Str\u00f6mung mitgeht \u2013 mit den Gef\u00fchlen, die es in eurem Leben gibt -, dann werdet ihr innerlich stiller, dann fragt ihr euch weniger: &#8222;Wie kann ich die Dinge ver\u00e4ndern? Wie kann ich die Dinge besser machen?&#8220; Dann seid ihr offener f\u00fcr das, was ist und was es euch jetzt gibt.<br><br>F\u00fchlt in diesem Moment einmal eine Emotion, die euch eurem Gef\u00fchl nach gerade st\u00f6rt oder behindert, eine Emotion, die euch Schwierigkeiten bereitet. Emotionen sind wie Wasser, sie k\u00f6nnen wie gro\u00dfe Wogen \u00fcber euch hinweg sp\u00fclen und es ist wichtig, eurer Kraft zu vertrauen, ohne in ihnen zu ertrinken. Das geht nur wenn ihr still werdet und wirklich ganz und gar zulasst, was die Emotion euch mitteilen m\u00f6chte. In der Emotion steckt ein Teil von eurer Seele, der eure Aufmerksamkeit bekommen m\u00f6chte.<br>\u00d6ffnet euch dieser Emotion, die euch im Alltag am meisten qu\u00e4lt. F\u00fchlt, was diese Emotion mit euch macht, wie sie euch k\u00f6rperlich ber\u00fchrt und bewegt und wie sie sich k\u00f6rperlich manifestiert.<br>Gebt dieser Emotion ein Wort, einen Namen. Ist es Angst? Ist es Unbehagen oder Frustration? Geht es um \u00c4rger oder Rebellion? Versucht euch dar\u00fcber klar zu werden, welche jetzt in eurem Leben die wichtigste Emotion ist. Denn sie ist eine Str\u00f6mung, die euch irgendwo hin f\u00fchren will.<br>Dann gebt dieser Emotion das Gesicht von einem Tier. Lasst ein Tier vor eurem inneren Auge erscheinen, das etwas von dieser Emotion zum Ausdruck bringt und damit die Sprache eurer Seele spricht. Hei\u00dft dieses Tier willkommen und schlie\u00dft Freundschaft mit ihm. F\u00fchlt vor allem, welche Lebenskraft dieses Tier durchstr\u00f6mt. Es will leben! Es steckt einfach nur ein wenig fest.<br>Sobald ihr den Kontakt mit diesem Tier hergestellt habt, geschieht etwas Magisches. Sobald ihr &#8222;Ja&#8220; zu euren Emotionen sagt, wie schwer oder unangenehm sie auch sein m\u00f6gen, findet Wachstum, Ver\u00e4nderung statt. Ihr entdeckt ein St\u00fcck von euch selbst, das zuvor nicht dasein durfte. Hinter Verlassenheit, Verzweiflung oder Wut steckt immer ein <em>wunderbares<\/em> St\u00fcck von euch selbst, das viel deutlicher gesehen werden m\u00f6chte. Lasst dies nun zum Vorschein kommen. F\u00fchlt, wo ihr euch selbst unterdr\u00fcckt.<br><br>Was immer auch in eurem Leben geschieht, welche \u00e4u\u00dferen Umst\u00e4nde auch eure Aufmerksamkeit einfordern, eure tiefste Mission oder Aufgabe im Leben ist es, immer mehr ihr selbst zu werden, euren tiefsten Kern zu entdecken und ihn den Menschen au\u00dferhalb von euch zu zeigen. Ganz und gar eure Arme um euren eigenen Reichtum zu legen, um das wer ihr seid, was ihr zu geben hast, und es dann freizusetzen in die Welt, darum geht es! Tiefe Emotionen wollen euch immer dorthin f\u00fchren, zu einem verborgenen Anteil in euch selbst, den ihr noch nicht vollst\u00e4ndig gesehen oder empfangen habt.<br><br>Es hat seine Gr\u00fcnde, warum es schwierig ist, zu diesem verborgenen Anteil zu gelangen. Tats\u00e4chlich werdet ihr in dieser Gesellschaft noch immer darin entmutigt und davon abgehalten, eure wahre Seele zu zeigen und danach zu leben. Es steckt in den Menschen noch immer viel Angst vor Echtheit, vor Authentizit\u00e4t, davor, ber\u00fchrt zu werden und gem\u00e4\u00df dem zu leben, was euch wirklich inspiriert und begeistert. Das ist f\u00fcr Menschen eine gro\u00dfe Herausforderung, weil sie sich an Sicherheiten aus der Vergangenheit festhalten &#8211; an bestimmten Denkmustern, Regeln, heiligen \u00dcberzeugungen -, oft aus Angst. Angst <em>gerade<\/em> vor Emotionen, vor Gef\u00fchlstiefe.<br><br>Wenn jemand erwacht, so wie ihr selbst es in euren Leben nun erlebt, dann bedeutet das, dass ihr f\u00fcr eure wirklichen Bed\u00fcrfnisse wach werdet, daf\u00fcr was eure Seele m\u00f6chte. Das bedeutet beinahe immer, dass ihr euch aus einer vertrauten Umgebung l\u00f6st und nicht mehr nach den gesellschaftlichen Kodizes und Gesetzen lebt, sondern mehr eurem eigenen Gef\u00fchl, eurer eigenen Inspiration folgt.<br><br>Wenn dies von eurer Umgebung nicht recht begriffen wird, dann kann das eurem Herzen Schmerzen verursachen und auch Selbstzweifel hervorrufen: \u201eMache ich es wirklich gut? Bin ich wirklich gut genug?\u201c Sehr tiefe Zweifel k\u00f6nnen dann nach oben kommen, denn ihr steht in gewisser Hinsicht allein da. Euch f\u00fcr den Weg der Seele zu entscheiden, bedeutet euch gegen Angst und auferlegte Urteile zu entscheiden. Es ist daher eine mutige Wahl, eine Entscheidung, die Mut und ein deutliches Ma\u00df an Traute erfordert, allein zu stehen.<br><br>F\u00fchlt in die Angst und den Zweifel hinein, die ihr in Bezug auf euch selbst habt. F\u00fchlt die Angst vor Einsamkeit und davor, versto\u00dfen zu werden, nicht dazu zu geh\u00f6ren. F\u00fchlt zugleich, dass es in euch eine gr\u00f6\u00dfere Kraft gibt, die dieses Risiko auf sich nehmen m\u00f6chte. Eine Kraft, die wei\u00df: \u201eIch muss dem Ruf meiner Seele folgen, denn das ist das Wichtigste, was es f\u00fcr mich zu tun gibt. Nur das macht mich wirklich gl\u00fccklich.\u201c<br>Ich m\u00f6chte euch wissen lassen, dass, wenn ihr diesem Weg folgt, ihr nicht allein seid. Es <em>scheint<\/em> lediglich so. Und es scheint auch nur <em>vor\u00fcbergehend<\/em> so. Die Erde ist mit euch. Die Erde m\u00f6chte euch in eurem Weg zur Selbstverwirklichung unterst\u00fctzen. Die Erde hat gro\u00dfes Interesse an eurer Seele. Sie m\u00f6chte eurer Seele helfen, in der Erde zu wurzeln, und sie erbl\u00fchen lassen.<br><br>Je mehr ihr euch f\u00fcr euch selbst entscheidet, desto tiefer wird der Kontakt mit eurer Seele. Auch daraus k\u00f6nnt ihr Trost und Unterst\u00fctzung sch\u00f6pfen, denn eure Seele ist voller Reichtum. Ihr seid mit anderen Sph\u00e4ren als der der Erde verbunden, Sph\u00e4ren voller Licht und Harmonie, wo sich eure F\u00fchrer aufhalten.<br><br>Ich bitte euch, das nun zu f\u00fchlen. F\u00fchlt eure eigene Seele in eurem Herzen. F\u00fchlt die Kraft, die gr\u00f6\u00dfer ist als die Pers\u00f6nlichkeit und die euch tr\u00e4gt. Es gibt etwas, das gr\u00f6\u00dfer ist und das alles zu euch hin anzieht, was zu euch geh\u00f6rt und euch hilft. Nehmt auch die geistigen F\u00fchrer wahr, die euch darin beistehen. Sie sind wie gute alte Freunde, die in diesem Moment nur in einer anderen Sph\u00e4re verkehren, sich nicht in einem k\u00f6rperlichen Dasein befinden.<br>Bittet dann um eine Botschaft aus dieser Sph\u00e4re, der Sph\u00e4re eurer Seele und eurer F\u00fchrer, aus der Sph\u00e4re aus der ihr gekommen seid und in die ihr nach eurem physischen Tod wieder zur\u00fcckkehrt. Diese Sph\u00e4re ist ganz nah bei euch, sie ist nicht weit fort oder \u00fcber euch erhaben. Diese Sph\u00e4re ist hier, hier und jetzt. Bittet um eine Licht-Botschaft, einen einfachen Satz oder ein Gef\u00fchl, etwas, das euch jetzt helfen kann. Vertraut darauf, dass, auch wenn es Dinge gibt, die nun unklar sind, das Leben euch allzeit nach Hause bringen m\u00f6chte: in den Kontakt mit eurer Seele, in den Kontakt mit der Einheit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a9&nbsp;Pamela Kribbe<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbersetzung:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\">Yvonne Mohr<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Pamela channelt Jeshua Liebe Menschen, ich bin Jeshua. Ich bin hier als ein Bruder und ein Lehrer. Ich bin mit euch verbunden und ich wei\u00df nur allzu gut, wie tief menschliche Emotionen sich anf\u00fchlen und wie sie euch von eurem Kern, von eurer Seele entfernen k\u00f6nnen. Ich bin selbst Mensch gewesen und habe in&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/folgt-dem-ruf-eurer-seele\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-743","post","type-post","status-publish","format-standard","hentry","category-am-morgen-mit-jeshua"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=743"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/743\/revisions"}],"predecessor-version":[{"id":744,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/743\/revisions\/744"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}