{"id":764,"date":"2022-10-06T08:15:03","date_gmt":"2022-10-06T08:15:03","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=764"},"modified":"2022-10-06T08:15:03","modified_gmt":"2022-10-06T08:15:03","slug":"newsletter-jeshua-net-oktober-2022","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-oktober-2022\/","title":{"rendered":"Newsletter Jeshua.net &#8211; Oktober 2022"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Liebe Leser<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben auf unserer Webseite zwei neue Channelings ver\u00f6ffentlicht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/isis\/ihr-seid-die-schoepfer-ich-bin-hier-um-euch-zu-unterstuetzen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ihr seid die Sch\u00f6pfer &#8211; Ich bin hier um Euch zu unterst\u00fctzen<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Isis, gechannelt durch Pamela Kribbe (\u00c4gypten)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8222;Gott oder das Einssein hatte, um es so zu sagen, den Wunsch, Dunkelheit, Trennung erschaffen, um so etwas Neues entstehen zu lassen. Denn wenn etwas Neues geboren wird, geschieht dies immer innerhalb der Dunkelheit. Es ist dann buchst\u00e4blich unbekanntes Gebiet, es ist absolut neu. Und ihr erforscht diese Dunkelheit, dieses unbekannte Land, indem ihr lebt, indem ihr hier auf der Erde seid.<br>Es war unvermeidlich, dass ihr verloren gingt, dass ihr euch auf eurer Reise verloren f\u00fchltet. Ihr befindet euch zwischen zwei Wirklichkeiten. Ihr wurdet aus der Einheit, aus einem Engels-Reich heraus geboren und auf eurer Reise seid ihr ins andere Extrem gegangen, ins Extrem der Trennung und dessen, euch verlassen und verloren zu f\u00fchlen. Die Bedeutung dieser Reise ist, dass ihr lernt, die Energien dieser beiden Extreme zusammenzubringen. Ihr seid nicht dazu bestimmt, einfach in die Ebene der Einheit zur\u00fcckkehren, aus der ihr gekommen seid. Euch ist bestimmt, Sch\u00f6pfer zu sein: etwas Neues zu erschaffen. Ihr bringt Licht und Leben in die Dunkelheit und in die Trennung hinein. Wenn ihr das in Zuversicht und Vertrauen tut, dann erkennt ihr, dass ihr ein Einssein in euch selbst geb\u00e4rt. Und genau das macht ihr gerade jetzt, in dieser Phase eurer Reise als Seele.&#8220;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/in-euch-moechte-die-saat-des-ganzseins-aufgehen\/\" target=\"_blank\" rel=\"noreferrer noopener\">In Euch m\u00f6chte die Saat des Ganzseins aufgehen<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jeshua, gechannelt durch Pamela Kribbe (\u00c4gypten)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8222;In der heutigen Welt werdet ihr mit der Erziehung und in der Schulausbildung, die ihr empfangt, von eurem inneren Selbst abgelenkt. Ihr entwickelt eine Pers\u00f6nlichkeit, die sich vor allem auf die Au\u00dfenwelt und die Gesellschaft fokussiert. Doch ihr seid erwachte Seelen und ihr seid nicht in der Lage, vollst\u00e4ndig zu vergessen, wer ihr wirklich seid. Deshalb f\u00fchlt ihr euch innerlich zerrissen, und die meisten von euch f\u00fchlen dies schon seit ihrer Kindheit.<br>Um vollst\u00e4ndig auf euer wahres Ich zugreifen zu k\u00f6nnen, m\u00fcsst ihr euch von vielen der Vorstellungen, die euch beigebracht wurden, befreien oder distanzieren. Ihr m\u00fcsst Abstand von der Art und Weise nehmen, wie ihr erzogen wurdet, oder euch sogar von ihr trennen. Ihr f\u00fchlt euch mit der Erziehung und der Ausbildung, die ihr erhaltet, oder mit den Jobs, die ihr macht, oftmals nicht zuhause. Der Teil eurer Seele, der euch ruft, f\u00fchrt euch fort von den allgemein\u00fcblichen Denkweisen und von der menschlichen Gesellschaft, und so scheint es, dass der Ruf eurer Seele euch in einen Raum der Einsamkeit und Trennung f\u00fchrt. Ihr m\u00f6chtet von einer Art von Energie und Schwingung gen\u00e4hrt werden, die in dieser Welt nicht zur Verf\u00fcgung zu stehen zu sein scheint.<br>Wenn ihr diesen Raum der Einsamkeit betretet, was im Laufe eures Lebens unvermeidbar ist, seid ihr zutiefst herausgefordert. Doch dieser Raum der Einsamkeit, des Gef\u00fchls, sich vom Mainstream-Bewusstsein zu unterscheiden, ist ein Tor zu einer anderen Bewusstseinsebene.&#8220;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Herzliche Gr\u00fc\u00dfe,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pamela und Gerrit<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Liebe Leser Wir haben auf unserer Webseite zwei neue Channelings ver\u00f6ffentlicht. Ihr seid die Sch\u00f6pfer &#8211; Ich bin hier um Euch zu unterst\u00fctzen Isis, gechannelt durch Pamela Kribbe (\u00c4gypten) &#8222;Gott oder das Einssein hatte, um es so zu sagen, den Wunsch, Dunkelheit, Trennung erschaffen, um so etwas Neues entstehen zu lassen. Denn wenn etwas&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-oktober-2022\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-764","post","type-post","status-publish","format-standard","hentry","category-newsletter"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=764"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/764\/revisions"}],"predecessor-version":[{"id":765,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/764\/revisions\/765"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}