{"id":772,"date":"2022-11-05T09:30:34","date_gmt":"2022-11-05T09:30:34","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=772"},"modified":"2022-11-05T09:30:34","modified_gmt":"2022-11-05T09:30:34","slug":"newsletter-jeshua-net-november-2022","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-november-2022\/","title":{"rendered":"Newsletter Jeshua.net &#8211; November 2022"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Liebe Leser<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben auf unserer Webseite zwei neue Channelings ver\u00f6ffentlicht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/du-wirst-zu-einem-lehrer\/\" target=\"_blank\" rel=\"noreferrer noopener\">Du wirst zu einem Lehrer<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Jeshua, gechannelt durch Pamela Kribbe<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8222;Ich habe Verst\u00e4ndnis f\u00fcr eure Angst. Aber ich ersuche euch, als ein Akt des Mitgef\u00fchls, vorzutreten und der Welt zu zeigen, wer ihr seid. Ihr m\u00fcsst das nicht tun. Ihr k\u00f6nnt auf euch selbst fokussiert bleiben, auf eure Heilung und darauf, euer eigenes Leben zu leben. Es existiert keine karmische Pflicht, in die Welt hinauszutreten. Aber ich appelliere an eure Liebe und euer Mitgef\u00fchl mit der Menschheit. Es ist gro\u00dfes Leid in dieser Welt. Viele Menschen f\u00fchlen sich in ihrem Schmerz verloren, sie ertrinken in ihrem Leid und sehen keinen Ausweg mehr. Und wenngleich ihr selbst eure eigenen Lasten tragt, habt ihr in euch selbst dennoch auch eine andere Ebene des Bewusstseins betreten. Ihr seid in der Lage, das Leiden Anderer zu erleichtern. Das liegt daran, dass ihr euch eures eigenen Schmerzes bewusst seid, dass euer Mitgef\u00fchl gewachsen ist und ihr kein Urteil \u00fcber andere Menschen f\u00e4llt. Euer eigener Schmerz kann eine Br\u00fccke zwischen euch und anderen Menschen sein. Wenn ihr etwas von euch selbst gebt, wenn ihr euer Licht, eure Seelen-Energie teilt, wird dies auch euch Heilung bringen. Indem ihr eure Energie mit der Menschheit teilt und ihr das Beste von euch anbietet, werdet ihr euch tiefer denn je mit der Menschheit verbunden f\u00fchlen.&#8220;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/jeshua.net\/de\/channelings\/maria-magdalena\/der-kampf-der-geschlechter\/\" target=\"_blank\" rel=\"noreferrer noopener\">Der Kampf der Geschlechter<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Maria Magdalena, gechannelt durch Pamela Kribbe<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8222;Ihr alle seid euch der j\u00fcngeren Geschichte bewusst, und mit j\u00fcngerer Geschichte meine ich die letzten vier- bis f\u00fcnftausend Jahre. W\u00e4hrend dieser Zeitspanne ist die weibliche Energie seitens einer aggressiven m\u00e4nnlichen Energie entwertet und erniedrigt worden. Im weiblichen Wesen hat dies eine Wunde auf einer sehr tiefen Ebene verursacht. Doch es hat auch die M\u00e4nner verletzt. Wegen der in dieser Epoche so pr\u00e4senten aggressiven m\u00e4nnlichen Energie waren M\u00e4nner nicht in der Lage, ihre sensible, weibliche Seite zu entwickeln. Es wurde schwierig f\u00fcr sie, sich aus dem Herzen heraus mit anderen Menschen zu verbinden und ihre Gef\u00fchle zu zeigen. Frauen hingegen verloren den Kontakt zu ihrem Selbstwertgef\u00fchl und ihrer Bevollm\u00e4chtigung. Und so entfernten und entfremdeten M\u00e4nner und Frauen sich voneinander wurde und die Sexualit\u00e4t, die der heiligste Bereich zwischen Mann und Frau ist, sehr verletzt. Statt wonnig und gl\u00fcckselig zu sein, wurde sie zu einem Bereich gro\u00dfer Schmerzen.&#8220;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Herzliche Gr\u00fc\u00dfe,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pamela und Gerrit<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Liebe Leser Wir haben auf unserer Webseite zwei neue Channelings ver\u00f6ffentlicht. Du wirst zu einem Lehrer Jeshua, gechannelt durch Pamela Kribbe &#8222;Ich habe Verst\u00e4ndnis f\u00fcr eure Angst. Aber ich ersuche euch, als ein Akt des Mitgef\u00fchls, vorzutreten und der Welt zu zeigen, wer ihr seid. Ihr m\u00fcsst das nicht tun. Ihr k\u00f6nnt auf euch&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/newsletter\/newsletter-jeshua-net-november-2022\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-772","post","type-post","status-publish","format-standard","hentry","category-newsletter"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=772"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/772\/revisions"}],"predecessor-version":[{"id":773,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/772\/revisions\/773"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}