{"id":937,"date":"2023-04-18T20:06:41","date_gmt":"2023-04-18T20:06:41","guid":{"rendered":"https:\/\/jeshua.net\/de\/?p=937"},"modified":"2023-04-18T20:06:41","modified_gmt":"2023-04-18T20:06:41","slug":"das-weisse-licht-des-bewusstseins-2","status":"publish","type":"post","link":"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/das-weisse-licht-des-bewusstseins-2\/","title":{"rendered":"Das wei\u00dfe Licht des Bewusstseins"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Jeshua, gechannelt durch Pamela Kribbe<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Menschen,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ich bin Jeshua, ich begr\u00fc\u00dfe euch alle an diesem sch\u00f6nen Tag auf dieser sch\u00f6nen Erde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht nur die Erde ist sch\u00f6n und reich an Leben und voller Ausgewogenheit. Ihr seid es ebenso. Ihr seid sch\u00f6n und rein im Inneren. Verbindet euch mit der Reinheit in euch, geht zu eurem Herzen.<br>Sinkt mit eurem Bewusstsein langsam in euer Herz hinein und ruht euch aus. Entlasst die Energien, die euch hemmen oder st\u00f6ren, die euch qu\u00e4len oder zur Last fallen, aus eurer Aufmerksamkeit. Sinkt in das Zentrum eures Herzens und f\u00fchlt, wer ihr seid, rein und unverf\u00e4lscht.<br>Aus diesem Zentrum heraus entsteht ein wei\u00dfes Licht. Seht dort eine Kugel oder ein rundes wei\u00dfes Licht in eurem Herzen erscheinen, seht es langsam gr\u00f6\u00dfer werden. Dieses Licht ist ewig, unersch\u00fctterlich. Es ist ein lebendiges Bewusstsein, das sieht und wahrnimmt und doch in seinem Wesen gleich bleibt.<br>Dieses Licht ist in mir und in euch und in jedem um euch herum. Das ist die Einheit, die uns verbindet. F\u00fchlt, dass dieses Bewusstsein nichts braucht, es ist einfach da. Lasst es euch von eurem Herzen aus durchstr\u00f6men, durch euren Bauch, durch euer Becken und eure Oberschenkel, eure Knie, eure Unterschenkel und Kn\u00f6chel und eure F\u00fc\u00dfe, bis es die Erde ber\u00fchrt. F\u00fchlt wie entspannend dieses Bewusstsein wirkt, weil es einfach <em>ist<\/em>. Lasst es auch in und um euren Kopf herum flie\u00dfen, denn dort besteht oft eine Menge Unruhe und Umtriebigkeit. Stellt euch vor, dass alle eure Gedanken von diesem wei\u00dfen Licht durchstr\u00f6mt werden, so dass die Gedanken, die euch nicht mehr dienen und \u00fcberfl\u00fcssig sind, einfach fortgewaschen werden. Ihr seid jetzt vollst\u00e4ndig aus wei\u00dfem Licht und ihr ruht euch aus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und von diesem wei\u00dfen Licht in eurem Herzen aus seht euch nun einmal um. Beginnt mit eurem K\u00f6rper. Sobald ihr dieses wei\u00dfe Licht seid, begreift ihr, dass euer K\u00f6rper ein <em>Teil<\/em> von euch ist, aber sicherlich nicht das Ganze. Das wei\u00dfe Licht, das ihr seid, ist unabh\u00e4ngig und lebt immer weiter, es ist unabh\u00e4ngig vom K\u00f6rper. Jetzt aber geh\u00f6rt euer K\u00f6rper zu dem, wer ihr seid, zu eurem Sein auf der Erde. Begr\u00fc\u00dft den K\u00f6rper aus der Mitte eures Herzens, aus dem stillen allgegenw\u00e4rtigen Licht heraus. Sagt &#8222;Hallo&#8220; zu eurem K\u00f6rper und fragt ihn, wie er sich f\u00fchlt, ob er sich wohlf\u00fchlt oder ob er irgendwo mehr Energie braucht. Lasst es dann dort m\u00fchelos in ihn hinein flie\u00dfen, das wei\u00dfe Licht des Bewusstseins ist unermesslich, unbeschr\u00e4nkt, grenzenlos, es gibt immer genug davon und es wird ganz von selbst dorthin gehen, wo es gebraucht wird. Ihr m\u00fcsst es daher nicht schieben oder dr\u00e4ngen, schon eure Aufmerksamkeit reicht aus. Seht, ob es einen Bereich in eurem K\u00f6rper gibt, der eure Aufmerksamkeit anzieht, und lasst m\u00fchelos Licht dorthin str\u00f6men.<br>Dann kehrt zum Zentrum eures Herzens zur\u00fcck, zu dem wei\u00dfen Licht, das stets dort lebt, dort gegenw\u00e4rtig ist und unersch\u00f6pflich ist. Ihr f\u00fchlt dieses Licht st\u00e4rker werden, es str\u00f6mt durch euren K\u00f6rper, aber auch aus ihm heraus. Es ist ein strahlend wei\u00dfes Licht. Euer gesamtes Energiefeld ist nun damit gef\u00fcllt. Und es ist gut, es ist in Ordnung, niemandem wird dadurch geschadet. Euer Licht darf scheinen wie es will. Dieses Licht habt ihr mit dem Menschen um euch herum, mit allem, was um euch herum lebendig ist, gemeinsam. Zeigt es ruhig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend ihr nun dieses wei\u00dfe Licht seid, seht euch weiter um. Ihr habt gerade euren K\u00f6rper angeschaut und ihn von innen gef\u00fchlt und gesehen. Nun schaut euch eure Beziehung zu einem der Menschen an, die euch in eurem Leben am n\u00e4chsten stehen. Es mag am einfachsten sein, jemanden auszuw\u00e4hlen, der euch jetzt besonders in den Sinn kommt, und dann zu sehen, was ihr wahrnehmt, wenn ihr von dem wei\u00dfen Licht, der Stille und Ruhe in eurem Herzen aus schaut, ohne etwas tun oder ver\u00e4ndern zu m\u00fcssen. Schaut diese Person aus diesem wei\u00dfen Licht, aus eurem Seelenbewusstsein heraus an. Wie ist es, nun mit dieser anderen Person zusammen zu sein, was ber\u00fchrt es in euch? F\u00fchlt ihr ein Ja von innen, wenn ihr hier mit ihr oder ihm zusammen seid? Schaut es euch aus dem Seelenlicht, aus eurem Herzen heraus an. Es mag auf Pers\u00f6nlichkeitsebene Dinge geben, in denen ihr mit einem anderen kollidiert, in denen es Schwierigkeiten oder Emotionen gibt, aber macht nun einen Schritt zur\u00fcck, betrachtet es aus einem geweiteten Bewusstsein heraus. Schaut euch die andere Person genau an, seht euch sein oder ihr Licht an und schaut, welche Bedeutung euer Zusammensein f\u00fcr euch hat. Bietet euch dieser andere Mensch etwas Wertvolles an? Und was bietet ihr dem anderen an?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schaut euch beide dort zusammen an und fragt euch dann, ob es da, energetisch gesehen, vielleicht einen Bereich gibt, der mehr Licht braucht, der mehr Bewusstsein zwischen euch beiden braucht. Lasst das wei\u00dfe Licht zu ihm oder ihr flie\u00dfen, ganz leicht, sanft und ohne Zwang. Bleibt ganz in eurem Licht, erkennt, dass ihr ein ewiges Wesen seid. Ihr seid nicht euer K\u00f6rper, ihr seid nicht eure Beziehungen. F\u00fchlt eure Unabh\u00e4ngigkeit und eure Kraft als kosmisches Wesen, als Seele. Lasst noch etwas mehr von diesem Seelenlicht zu, es ist wie in euch selbst nach Hause zu kommen, lasst es ruhig geschehen. Das Licht, das ihr aussendet, wird noch einmal gr\u00f6\u00dfer. Ihr f\u00fchlt euch wohl und ruhig, denn alles ist gut und nichts muss geschehen und das Licht durchstr\u00f6mt euch.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dann schaut noch weiter, betrachtet euer t\u00e4gliches Leben im Bereich eurer Arbeit oder eurer t\u00e4glichen Besch\u00e4ftigungen, das, womit ihr jeden Tag besch\u00e4ftigt seid. Werdet wieder still von innen, nehmt all dies nicht als etwas Pers\u00f6nliches wahr. Wenn es dort st\u00f6rende Gef\u00fchle, Schmerzen oder Belastungen gibt, dann erkennt, dass ihr diese nicht <em>seid<\/em>. Ihr seid eine ewige Seele, die sich vor\u00fcbergehend in den Tanz mit dieser Welt begibt. Indem ihr erkennt, wer ihr seid, eure Kraft, eure Gr\u00f6\u00dfe, eure Unabh\u00e4ngigkeit erkennt, wird das Leben mehr wie ein Spiel, wie ein Tanz sein, in den ihr euch aus eurer Kraft, eurer bewussten Wahl heraus begebt, und nicht wie etwas, was euch einfach nur zust\u00f6\u00dft oder \u00fcberkommt. Ihr k\u00f6nnt w\u00e4hlen! Dann schaut euch den Bereich der Arbeit und der Kreativit\u00e4t an. F\u00fchlt, ob euer Licht, euer nat\u00fcrliches Selbst durch sie und in ihnen str\u00f6men kann. Gibt das, was ihr tut, euch Nahrung, Inspiration? Wird euer Licht dadurch st\u00e4rker, strahlt ihr dadurch mehr?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Welt sein, erkennen, dass das Licht eurer Seele alles durchstrahlt, was ihr tut, dass es in eurem K\u00f6rper und in der Art und Weise leuchtet, wie ihr mit eurem K\u00f6rper interagiert, in euren Beziehungen und darin, wie ihr auf Menschen in eurer Arbeit reagiert, und ob ihr dort wagt, zu sein wer ihr seid &#8211; in der Str\u00f6mung von innen nach au\u00dfen, darin liegt, aus Sicht der Seele, eure Aufgabe. In der Welt zu <em>sein<\/em> ist eine Bewegung von innen nach au\u00dfen. Es ist eine nat\u00fcrliche Bewegung. Es liegt nicht in eurer Natur, eure Kraft, eure Energie in euch zu behalten. Das ist kontraproduktiv. Ihr wurdet geboren, um hier zu <em>sein<\/em>, um von innen heraus zu strahlen, um das Licht von innen nach au\u00dfen zu bringen. Das ist die Bedeutung und Erf\u00fcllung eures Lebens hier. Und darum f\u00fchlt ihr euch, wenn ihr es nicht tut, klein, ungl\u00fccklich und unerf\u00fcllt. Euer R\u00fcckzug aus der Welt, der oft aus der Angst heraus geschieht, widerspricht eurem Lebensziel, eurer Erf\u00fcllung. F\u00fchlt, dass die Kraft von innen nach au\u00dfen treten m\u00f6chte. Dieses wei\u00dfe Licht in eurem Herzen, im Zentrum dessen, wer ihr seid, hat gew\u00e4hlt, in den Tanz mit der Erde und mit den Menschen auf der Erde einzutreten. F\u00fchlt das Ja! in diesem Licht im Zentrum eures Herzens. Dort ist eine Weisheit, ein Wissen, dass alles gut ist, und dass ihr alles bew\u00e4ltigen k\u00f6nnt, dass ihr diese alten \u00c4ngste durchleben und hinter euch lassen k\u00f6nnt. Das ist eure Aufgabe, eure Mission.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fchlt, wie dieses Licht in eurem Herzen, dieses wei\u00dfe Licht, uns alle verbindet, und f\u00fchlt die Kraft unseres Zusammenseins. Stellt euch vor, wie die Grenzen verschwimmen und wie das Licht unserer Seelen jetzt wie <em>eine<\/em> B\u00fcndelung von Kraft zerflie\u00dft. Ruht aus, badet in diesem Licht. Ihr m\u00fcsst dieses Licht nicht eigens erschaffen oder visualisieren. Es ist einfach da, es ist wer ihr seid, wer ihr <em>alle<\/em> seid. Es ist wie ein gro\u00dfes Meer aus funkelndem Licht. F\u00fchlt auch einmal die Freude, die von Natur aus in diesem Licht lebt. Es ist ein ruhiges, aufmerksames, konzentriertes Licht, aber wenn ihr in dieses Licht hineingeht, dann sp\u00fcrt ihr auch den Glanz, das Funkeln des Lebens, das tanzen und Abenteuer erleben m\u00f6chte, das <em>sein<\/em> und sich manifestieren will.<br>Die Seele ist unendlich stark und mutig und hat so viel Kraft zu ihrer Verf\u00fcgung. F\u00fchlt das! F\u00fchlt, dass ihr euch aus dem Kern dessen, wer ihr seid, <em>f\u00fcr<\/em> euer Leben entscheiden k\u00f6nnt, dass ihr selbst der Beziehung zu eurem K\u00f6rper, der Beziehung zu Menschen, der Beziehung zu eurer Arbeit Form geben k\u00f6nnt. Ihr seid stark! Sonst w\u00e4rt ihr nicht hier. Den Sprung in die irdische Inkarnation zu wagen, zeugt von enormem Mut, Ausdauer und Vertrauen in eure tiefste Weisheit, wenn ihr auch wisst, dass ihr diese dann, w\u00e4hrend ihr auf der Erde seid, m\u00f6glicherweise nicht mehr wahrnehmt. Schenkt euch selbst ein gro\u00dfes Kompliment daf\u00fcr, wer ihr seid und was ihr euch traut.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und denkt daran, dass ihr immer zu diesem Ort in der Mitte eures Herzens zur\u00fcckkehren k\u00f6nnt, dem Zentrum, von dem aus ihr mit allem verbunden seid. Ruht euch dort aus. F\u00fchlt wie relativ alles ist. Alles lebt und bewegt sich und flie\u00dft, und ihr nehmt teil am Leben. Gleichzeitig seid ihr dieses ewige Licht, unverg\u00e4nglich, nicht gebunden an Zeit und Raum, an diesen K\u00f6rper oder dieses Leben. Ihr seid nicht hier, weil ihr hier sein m\u00fcsst, sondern weil ihr hier sein <em>wollt<\/em>, weil ihr eine Wahl getroffen habt. Vertraut dem! Es gibt einen Lebensplan f\u00fcr euch, eure Seele hat dies gew\u00e4hlt, vertraut dem Weg. Es gibt absolut einen Platz f\u00fcr euch auf der Erde und ihr findet ihn, indem ihr an euch selbst glaubt, an euren eigenen Mut, an eure eigene Kraft, an euer eigenes Wissen glaubt. Ihr habt alles was ihr braucht. Glaubt an euch selbst!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a9&nbsp;Pamela Kribbe<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbersetzung:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.lichtderwelten.de\/\" target=\"_blank\">Yvonne Mohr<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"2\" tabindex=\"0\" role=\"region\" aria-label=\"Slider\"><div id=\"n2-ss-2-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-2\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 400\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"4\" data-slide-public-id=\"1\" data-title=\"Slide 1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-4\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">Slide 1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-gYm63DmCSmr2\" data-sstype=\"slide\" data-pm=\"default\"><div class=\"n2-ss-layer n2-ow n-uc-gel0SRMgsshM\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-469\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"238\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item1\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"316\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/vf220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-5inua9QpaLve\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-234\" data-desktopportraittop=\"-37\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item2\" alt=\"\" class=\"skip-lazy\" width=\"220\" height=\"314\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/nms220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-OcFhELUzmxzV\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"0\" data-desktopportraittop=\"-39\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item3\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"313\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/Cover-online_LadH220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-3BAsFvHUnLWd\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"234\" data-desktopportraittop=\"-38\" data-responsivesize=\"1\" data-desktopportraitwidth=\"220\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item4\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"220\" height=\"315\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/cover-ic220.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-kbRl36oHYzkU\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"470\" data-desktopportraittop=\"-36\" data-responsivesize=\"1\" data-desktopportraitwidth=\"231\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\" n2-ss-item-image-content n2-ss-item-content n2-ow-all\"><a style=\"width:100%\" href=\"https:\/\/jeshua.net\/de\/bucher\/bucher\/\"><img loading=\"lazy\" decoding=\"async\" id=\"n2-ss-2item5\" alt=\"\" class=\"skip-lazy\" style=\"width:100%;height:auto\" width=\"231\" height=\"318\" data-skip-lazy=\"1\" src=\"\/\/jeshua.net\/de\/wp\/wp-content\/uploads\/2020\/01\/jeshua-cover1.jpg\" \/><\/a><\/div><\/div><div class=\"n2-ss-layer n2-ow n-uc-22SSnKFQsLmG n2-ss-layer--auto\" data-pm=\"absolute\" data-responsiveposition=\"1\" data-desktopportraitleft=\"-331\" data-desktopportraittop=\"179\" data-responsivesize=\"1\" data-desktopportraitwidth=\"319\" data-desktopportraitheight=\"auto\" data-desktopportraitalign=\"center\" data-desktopportraitvalign=\"middle\" data-parentid=\"\" data-desktopportraitparentalign=\"center\" data-desktopportraitparentvalign=\"middle\" data-sstype=\"layer\"><div class=\"n2-ss-button-container n2-ss-item-content n2-ow n2-font-1a7f5ed23c7fb336c5040a6b4265ed95-link  n2-ss-nowrap n2-ss-button-container--non-full-width\"><a class=\"n2-style-71fd4baf25a1f418142b73ce65617c0c-heading  n2-ow \" href=\"https:\/\/jeshua.net\/de\/Buch-Geistfuehrer-v.pdf\"><div><div>Kontakt mit Geistf\u00fchrern  (Kostenloser Download)<\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Jeshua, gechannelt durch Pamela Kribbe Liebe Menschen, ich bin Jeshua, ich begr\u00fc\u00dfe euch alle an diesem sch\u00f6nen Tag auf dieser sch\u00f6nen Erde. Nicht nur die Erde ist sch\u00f6n und reich an Leben und voller Ausgewogenheit. Ihr seid es ebenso. Ihr seid sch\u00f6n und rein im Inneren. Verbindet euch mit der Reinheit in euch, geht&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/jeshua.net\/de\/channelings\/am-morgen-mit-jeshua\/das-weisse-licht-des-bewusstseins-2\/\"> Read More<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-937","post","type-post","status-publish","format-standard","hentry","category-am-morgen-mit-jeshua"],"_links":{"self":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/comments?post=937"}],"version-history":[{"count":1,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/937\/revisions"}],"predecessor-version":[{"id":938,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/posts\/937\/revisions\/938"}],"wp:attachment":[{"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/media?parent=937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/categories?post=937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jeshua.net\/de\/wp-json\/wp\/v2\/tags?post=937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}